{"id":4880,"date":"2025-04-03T13:36:38","date_gmt":"2025-04-03T13:36:38","guid":{"rendered":"http:\/\/localhost\/adv\/?page_id=4880"},"modified":"2025-05-11T10:56:56","modified_gmt":"2025-05-11T10:56:56","slug":"home-one-2","status":"publish","type":"page","link":"https:\/\/www.angleadvt.com\/leo9\/","title":{"rendered":"Home New"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4880\" class=\"elementor elementor-4880\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a92b298 elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"a92b298\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=Y1BmjPeatI4&quot;,&quot;background_play_once&quot;:&quot;yes&quot;,&quot;background_video_start&quot;:10,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-embed\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8c6c1de\" data-id=\"8c6c1de\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e87890 elementor-widget elementor-widget-heading\" data-id=\"1e87890\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">We are an end-to-end marketing firm building <b>impactful relationships<\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0dcf83b elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"0dcf83b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3fb53976 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3fb53976\" data-element_type=\"section\" id=\"about\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-577a97fc\" data-id=\"577a97fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4f5030b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f5030b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9000ef6\" data-id=\"9000ef6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4459c6b elementor-widget elementor-widget-heading\" data-id=\"4459c6b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">About us<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-768e98ae elementor-widget elementor-widget-heading\" data-id=\"768e98ae\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Who we are & What we do<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a10daaf\" data-id=\"a10daaf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-909dcd1 elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"909dcd1\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3c2988f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c2988f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-20e83b3\" data-id=\"20e83b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11a74a1b elementor-widget elementor-widget-text-editor\" data-id=\"11a74a1b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Leo9 is the next chapter in the evolution of Angle Advertising, pushing into new markets while staying grounded in the creativity and expertise that have defined us. With offices across India and the UK, we\u2019re broadening our global reach, collaborating with brands worldwide, and driving the future of marketing.<\/p><p>Our philosophy is built on strong partnerships with like-minded individuals. As bold creatives, we push boundaries and turn big ideas into real impact. We believe that authentic relationships drive success, which is why we put people first\u2014whether fostering connections with clients, teaming up with strategic partners, or empowering our team.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7338254\" data-id=\"7338254\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20bfb2a elementor-widget elementor-widget-text-editor\" data-id=\"20bfb2a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAt Leo9 Advertising, we make marketing seamless by offering a full spectrum of services all under one roof. We don\u2019t just build brands\u2014we foster relationships that drive lasting impact.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88c6856 elementor-widget elementor-widget-image\" data-id=\"88c6856\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"2352\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/about-image-scaled.png\" class=\"attachment-full size-full wp-image-5256\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/about-image-scaled.png 2560w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/about-image-300x276.png 300w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/about-image-1024x941.png 1024w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/about-image-768x706.png 768w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/about-image-1536x1411.png 1536w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/about-image-2048x1882.png 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d6729e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6d6729e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-88f3fc4\" data-id=\"88f3fc4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c5185b elementor-widget elementor-widget-deensimc-smooth-text\" data-id=\"4c5185b\" data-element_type=\"widget\" data-widget_type=\"deensimc-smooth-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"deensimc-wrapper deensimc-wrapper-horizontal deensimc-text-marquee\">\n\t\t\t<div class=\"deensimc-marquee deensimc-no-shadow deensimc-marquee-horizontal \" data-pause-on-hover=\"\" data-animation-speed=\"3000\" >\n\t\t\t\t<div class=\"deensimc-marquee-group\">\n\t\t\t\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\"><path d=\"M0 0 C0.98797577 -0.0127597 1.97595154 -0.02551941 2.99386597 -0.03866577 C4.06468414 -0.04089142 5.13550232 -0.04311707 6.23876953 -0.04541016 C7.33625519 -0.05206696 8.43374084 -0.05872375 9.56448364 -0.06558228 C11.88965169 -0.07572214 14.21484892 -0.08039889 16.54003906 -0.08007812 C20.10026007 -0.08444649 23.6592372 -0.1207404 27.21923828 -0.15869141 C29.47574445 -0.16456016 31.73225652 -0.16852916 33.98876953 -0.17041016 C35.05553925 -0.18478119 36.12230896 -0.19915222 37.22140503 -0.21395874 C44.59787522 -0.16830829 44.59787522 -0.16830829 47.92578125 2.18554688 C50.11186083 5.66953544 49.51550473 8.25668689 49.24658203 12.29052734 C46.60658203 12.29052734 43.96658203 12.29052734 41.24658203 12.29052734 C40.58658203 13.61052734 39.92658203 14.93052734 39.24658203 16.29052734 C36.37158203 16.47802734 36.37158203 16.47802734 33.24658203 16.29052734 C32.58658203 15.30052734 31.92658203 14.31052734 31.24658203 13.29052734 C28.83087073 12.78148351 28.83087073 12.78148351 26.02001953 12.77880859 C24.98876953 12.74335937 23.95751953 12.70791016 22.89501953 12.67138672 C21.81478516 12.64882813 20.73455078 12.62626953 19.62158203 12.60302734 C18.53361328 12.56886719 17.44564453 12.53470703 16.32470703 12.49951172 C13.6321014 12.416844 10.93982912 12.34775647 8.24658203 12.29052734 C7.58658203 10.97052734 6.92658203 9.65052734 6.24658203 8.29052734 C4.26658203 8.29052734 2.28658203 8.29052734 0.24658203 8.29052734 C-0.41341797 9.61052734 -1.07341797 10.93052734 -1.75341797 12.29052734 C-3.40341797 12.29052734 -5.05341797 12.29052734 -6.75341797 12.29052734 C-6.80737275 10.66588892 -6.84618992 9.04074193 -6.87841797 7.41552734 C-6.90162109 6.51060547 -6.92482422 5.60568359 -6.94873047 4.67333984 C-6.56949959 0.04672306 -3.99030774 0.03489635 0 0 Z M33.24658203 7.29052734 C33.24658203 7.62052734 33.24658203 7.95052734 33.24658203 8.29052734 C35.22658203 8.29052734 37.20658203 8.29052734 39.24658203 8.29052734 C39.24658203 7.96052734 39.24658203 7.63052734 39.24658203 7.29052734 C37.26658203 7.29052734 35.28658203 7.29052734 33.24658203 7.29052734 Z M31.24658203 9.29052734 C32.24658203 11.29052734 32.24658203 11.29052734 32.24658203 11.29052734 Z \" fill=\"#FFFFFF\" transform=\"translate(10.75341796875,43.70947265625)\"><\/path><path d=\"M0 0 C18.48 0 36.96 0 56 0 C56 1.98 56 3.96 56 6 C37.52 6 19.04 6 0 6 C0 4.02 0 2.04 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(4,4)\"><\/path><path d=\"M0 0 C1.32 0 2.64 0 4 0 C4 1.32 4 2.64 4 4 C5.2065625 4.185625 5.2065625 4.185625 6.4375 4.375 C7.7059375 4.684375 7.7059375 4.684375 9 5 C10.38550197 7.77100394 10.1877467 9.9334706 10 13 C9.01 14.485 9.01 14.485 8 16 C6.68 16 5.36 16 4 16 C4 13.69 4 11.38 4 9 C2.68 9 1.36 9 0 9 C0 11.31 0 13.62 0 16 C-2.4375 15.625 -2.4375 15.625 -5 15 C-6.38550197 12.22899606 -6.1877467 10.0665294 -6 7 C-5.34 6.01 -4.68 5.02 -4 4 C-2.68 4 -1.36 4 0 4 C0 2.68 0 1.36 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(50,26)\"><\/path><path d=\"M0 0 C2.64 0 5.28 0 8 0 C8 3.3 8 6.6 8 10 C5.36 10 2.72 10 0 10 C0 6.7 0 3.4 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(6,12)\"><\/path><path d=\"M0 0 C1.51400391 0.01740234 1.51400391 0.01740234 3.05859375 0.03515625 C4.07050781 0.04417969 5.08242188 0.05320313 6.125 0.0625 C7.29869141 0.07990234 7.29869141 0.07990234 8.49609375 0.09765625 C8.49609375 2.07765625 8.49609375 4.05765625 8.49609375 6.09765625 C3.87609375 6.09765625 -0.74390625 6.09765625 -5.50390625 6.09765625 C-3.11341497 0.12142804 -3.11341497 0.12142804 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(19.50390625,35.90234375)\"><\/path><path d=\"M0 0 C3.96 0 7.92 0 12 0 C12 1.98 12 3.96 12 6 C8.04 6 4.08 6 0 6 C0 4.02 0 2.04 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(4,24)\"><\/path><path d=\"M0 0 C3.96 0 7.92 0 12 0 C12 1.98 12 3.96 12 6 C8.04 6 4.08 6 0 6 C0 4.02 0 2.04 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(46,18)\"><\/path><path d=\"M0 0 C7.82152466 -0.92017937 7.82152466 -0.92017937 10.7109375 1.3359375 C12.0625 3 12.0625 3 14 6 C9.38 6 4.76 6 0 6 C0 4.02 0 2.04 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(30,36)\"><\/path><path d=\"M0 0 C3 0.125 3 0.125 4 1.125 C4.125 4.125 4.125 4.125 4 7.125 C3 8.125 3 8.125 0 8.25 C-3 8.125 -3 8.125 -4 7.125 C-4.125 4.125 -4.125 4.125 -4 1.125 C-3 0.125 -3 0.125 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(14,51.875)\"><\/path><path d=\"M0 0 C1.32 0 2.64 0 4 0 C4 2.64 4 5.28 4 8 C2.68 8 1.36 8 0 8 C0 5.36 0 2.72 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(8,32)\"><\/path><path d=\"M0 0 C2.64 0 5.28 0 8 0 C8 1.32 8 2.64 8 4 C5.36 4 2.72 4 0 4 C0 2.68 0 1.36 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(48,12)\"><\/path><\/svg>\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tAutomotive\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\"><path d=\"M0 0 C7.09046636 4.26619657 12.00533128 9.23677697 14.77734375 17.1328125 C16.91786934 26.22687981 15.97967358 34.77076366 11.4375 42.9375 C10.674375 43.88625 9.91125 44.835 9.125 45.8125 C7.20159051 47.74767091 7.20159051 47.74767091 7.5625 49.9375 C8.21281278 51.4239292 8.88259461 52.90187165 9.5625 54.375 C10.4375 56.9375 10.4375 56.9375 9.4375 61.9375 C-5.7425 61.9375 -20.9225 61.9375 -36.5625 61.9375 C-37.68995253 56.30023735 -37.00967364 55.72988171 -34.5625 50.9375 C-34.97472769 47.4188422 -36.70399688 44.83698935 -38.5625 41.875 C-43.31443576 34.27875654 -43.82446333 26.26719007 -42.06640625 17.44921875 C-40.46329882 12.78481014 -37.85318901 9.49500163 -34.5625 5.9375 C-33.5725 6.2675 -32.5825 6.5975 -31.5625 6.9375 C-32.2225 8.2575 -32.8825 9.5775 -33.5625 10.9375 C-32.9025 11.39125 -32.2425 11.845 -31.5625 12.3125 C-30.9025 12.84875 -30.2425 13.385 -29.5625 13.9375 C-29.5625 14.5975 -29.5625 15.2575 -29.5625 15.9375 C-28.634375 16.185 -27.70625 16.4325 -26.75 16.6875 C-23.37875958 18.00955507 -22.16607433 18.73035135 -20.5625 21.9375 C-20.875 24.1875 -20.875 24.1875 -21.5625 25.9375 C-23.8725 26.2675 -26.1825 26.5975 -28.5625 26.9375 C-29.0575 29.4125 -29.0575 29.4125 -29.5625 31.9375 C-35.1875 32.1875 -35.1875 32.1875 -38.5625 29.9375 C-37.2425 33.5675 -35.9225 37.1975 -34.5625 40.9375 C-31.54166999 41.06119162 -31.54166999 41.06119162 -28.625 40.1875 C-25.5625 39.9375 -25.5625 39.9375 -23.25 41.625 C-21.63402381 43.83948589 -20.94570557 45.25506099 -20.5625 47.9375 C-20.665625 47.050625 -20.76875 46.16375 -20.875 45.25 C-20.5625 41.9375 -20.5625 41.9375 -18.4375 39 C-15.5625 36.9375 -15.5625 36.9375 -12.4375 36.875 C-9.0998595 38.10847584 -8.0810918 38.73158397 -6.5625 41.9375 C-6.375 45.6875 -6.375 45.6875 -6.5625 48.9375 C-6.294375 47.82375 -6.02625 46.71 -5.75 45.5625 C-4.5625 41.9375 -4.5625 41.9375 -1.5625 39.9375 C1.4375 40.3125 1.4375 40.3125 4.4375 40.9375 C5.4275 40.9375 6.4175 40.9375 7.4375 40.9375 C9.0875 36.6475 10.7375 32.3575 12.4375 27.9375 C9.4675 28.4325 9.4675 28.4325 6.4375 28.9375 C4.0625 27.5 4.0625 27.5 2.4375 25.9375 C2.045625 26.453125 1.65375 26.96875 1.25 27.5 C-0.5625 28.9375 -0.5625 28.9375 -3.125 28.9375 C-5.5625 27.9375 -5.5625 27.9375 -6.5625 25.5625 C-7.0575 24.263125 -7.0575 24.263125 -7.5625 22.9375 C-10.43852678 20.81832237 -13.05297825 19.58741143 -16.5625 18.9375 C-17.49673645 15.92718256 -17.60699911 15.07099732 -16.5625 11.9375 C-14.5 11.25 -14.5 11.25 -12.5625 10.9375 C-12.5625 9.9475 -12.5625 8.9575 -12.5625 7.9375 C-13.8825 7.6075 -15.2025 7.2775 -16.5625 6.9375 C-16.8925 5.2875 -17.2225 3.6375 -17.5625 1.9375 C-22.0175 2.4325 -22.0175 2.4325 -26.5625 2.9375 C-26.5625 1.9475 -26.5625 0.9575 -26.5625 -0.0625 C-18.84018593 -3.78175765 -7.76587467 -3.63203985 0 0 Z M-13.5625 0.9375 C-13.29573796 2.92241642 -13.29573796 2.92241642 -12.5625 4.9375 C-11.5725 5.2675 -10.5825 5.5975 -9.5625 5.9375 C-9.5625 8.5775 -9.5625 11.2175 -9.5625 13.9375 C-10.5525 14.2675 -11.5425 14.5975 -12.5625 14.9375 C-10.17676621 16.82963369 -8.49074652 17.96141783 -5.5625 18.9375 C-3.875 22 -3.875 22 -2.5625 24.9375 C-1.9025 23.6175 -1.2425 22.2975 -0.5625 20.9375 C5.1875 22.6875 5.1875 22.6875 7.4375 24.9375 C9.54570797 24.6189823 9.54570797 24.6189823 11.4375 23.9375 C11.00492927 17.01636824 8.66118732 11.94229497 3.5390625 7.16796875 C-1.77031513 2.98759671 -6.65364434 0.53109673 -13.5625 0.9375 Z M-36.5625 14.9375 C-37.09440541 16.37094 -37.61265258 17.80945367 -38.125 19.25 C-38.41503906 20.05050781 -38.70507812 20.85101563 -39.00390625 21.67578125 C-39.81165625 24.0808174 -39.81165625 24.0808174 -38.5625 26.9375 C-36.9125 26.9375 -35.2625 26.9375 -33.5625 26.9375 C-33.2325 25.2875 -32.9025 23.6375 -32.5625 21.9375 C-30.9125 21.6075 -29.2625 21.2775 -27.5625 20.9375 C-31.39331939 16.75572976 -31.39331939 16.75572976 -36.5625 14.9375 Z M-27.5625 20.9375 C-27.2325 21.5975 -26.9025 22.2575 -26.5625 22.9375 C-25.9025 22.6075 -25.2425 22.2775 -24.5625 21.9375 C-25.5525 21.6075 -26.5425 21.2775 -27.5625 20.9375 Z M-15.5625 40.9375 C-16.91868499 42.06284105 -16.91868499 42.06284105 -16.625 45 C-16.604375 45.969375 -16.58375 46.93875 -16.5625 47.9375 C-14.90635343 48.31968767 -13.23792976 48.65145102 -11.5625 48.9375 C-10.20631501 47.81215895 -10.20631501 47.81215895 -10.5 44.875 C-10.520625 43.905625 -10.54125 42.93625 -10.5625 41.9375 C-12.21864657 41.55531233 -13.88707024 41.22354898 -15.5625 40.9375 Z M-29.5625 43.9375 C-29.8925 45.5875 -30.2225 47.2375 -30.5625 48.9375 C-28.5825 49.9275 -28.5825 49.9275 -26.5625 50.9375 C-25.26616379 49.87104885 -25.26616379 49.87104885 -25.5 47.375 C-25.520625 46.570625 -25.54125 45.76625 -25.5625 44.9375 C-26.8825 44.6075 -28.2025 44.2775 -29.5625 43.9375 Z M-0.5625 43.9375 C-1.85883621 45.00395115 -1.85883621 45.00395115 -1.625 47.5 C-1.604375 48.304375 -1.58375 49.10875 -1.5625 49.9375 C-0.2425 49.9375 1.0775 49.9375 2.4375 49.9375 C2.7675 48.2875 3.0975 46.6375 3.4375 44.9375 C1.49146726 44.34679986 1.49146726 44.34679986 -0.5625 43.9375 Z M-18.5625 51.9375 C-20.93230013 54.89127498 -20.93230013 54.89127498 -20.5625 58.9375 C-15.9425 58.9375 -11.3225 58.9375 -6.5625 58.9375 C-7.25552969 54.33217611 -7.25552969 54.33217611 -8.5625 51.9375 C-10.18668745 51.85659029 -11.81201745 51.79835005 -13.4375 51.75 C-14.34242187 51.71519531 -15.24734375 51.68039063 -16.1796875 51.64453125 C-16.96601563 51.74121094 -17.75234375 51.83789062 -18.5625 51.9375 Z M-32.5625 53.9375 C-32.8925 55.5875 -33.2225 57.2375 -33.5625 58.9375 C-30.2625 58.9375 -26.9625 58.9375 -23.5625 58.9375 C-23.5625 57.2875 -23.5625 55.6375 -23.5625 53.9375 C-26.5325 53.9375 -29.5025 53.9375 -32.5625 53.9375 Z M-3.5625 53.9375 C-3.5625 55.5875 -3.5625 57.2375 -3.5625 58.9375 C-0.2625 58.9375 3.0375 58.9375 6.4375 58.9375 C6.1075 57.2875 5.7775 55.6375 5.4375 53.9375 C2.4675 53.9375 -0.5025 53.9375 -3.5625 53.9375 Z \" fill=\"#FFFFFF\" transform=\"translate(45.5625,2.0625)\"><\/path><path d=\"M0 0 C1.32 0 2.64 0 4 0 C4 0.99 4 1.98 4 3 C2.68 2.67 1.36 2.34 0 2 C0 1.34 0 0.68 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(14,5)\"><\/path><\/svg>\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tCulture\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\"><path d=\"M0 0 C1.14339844 0.38285156 2.28679688 0.76570312 3.46484375 1.16015625 C4.54894531 1.54558594 5.63304687 1.93101563 6.75 2.328125 C7.73484375 2.67262695 8.7196875 3.01712891 9.734375 3.37207031 C12 4.75 12 4.75 12.828125 7.40136719 C12.88484375 8.17641602 12.9415625 8.95146484 13 9.75 C8.86327942 11.35539152 4.71916779 12.93940294 0.56713867 14.50463867 C-0.8422698 15.03928646 -2.24955231 15.57957565 -3.65454102 16.12573242 C-5.682241 16.91280491 -7.71688782 17.67882803 -9.75390625 18.44140625 C-10.97408447 18.90748291 -12.1942627 19.37355957 -13.45141602 19.85375977 C-19.68944622 21.42925401 -24.71485988 19.68553143 -30.58984375 17.46484375 C-32.38325195 16.79291992 -32.38325195 16.79291992 -34.21289062 16.10742188 C-35.44201172 15.63884766 -36.67113281 15.17027344 -37.9375 14.6875 C-39.20613503 14.20963505 -40.4750134 13.73241559 -41.74414062 13.25585938 C-44.83187615 12.09355589 -47.91698986 10.92476771 -51 9.75 C-50.86914062 7.41943359 -50.86914062 7.41943359 -50 4.75 C-47.45898438 3.24853516 -47.45898438 3.24853516 -44.09375 2.0390625 C-42.87429687 1.59949219 -41.65484375 1.15992188 -40.3984375 0.70703125 C-39.75745117 0.48869629 -39.11646484 0.27036133 -38.45605469 0.04541016 C-36.52415101 -0.61672258 -34.61062986 -1.3188642 -32.6953125 -2.02734375 C-19.90756781 -6.51779917 -12.51481915 -4.48097233 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(51,10.25)\"><\/path><path d=\"M0 0 C1.17175781 0.46792969 2.34351563 0.93585937 3.55078125 1.41796875 C12.94327645 4.98181269 19.42052408 7.27821255 29 3 C30.72453889 2.42346794 32.45354591 1.86006445 34.1875 1.3125 C35.445625 0.879375 36.70375 0.44625 38 0 C38 3.96 38 7.92 38 12 C31.40819368 15.44571694 26.5613888 16.20221315 19.25 16.25 C18.4765625 16.270625 17.703125 16.29125 16.90625 16.3125 C10.51428525 16.35539909 5.74048451 14.87024225 0 12 C0 8.04 0 4.08 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(13,27)\"><\/path><path d=\"M0 0 C0.06058594 1.16917969 0.12117188 2.33835937 0.18359375 3.54296875 C0.26804034 5.09115614 0.35268625 6.63933268 0.4375 8.1875 C0.47681641 8.95642578 0.51613281 9.72535156 0.55664062 10.51757812 C0.73590188 13.73049144 0.95241858 16.76706874 1.59765625 19.92578125 C2 22 2 22 1 24 C0.77377919 25.70363822 0.59111527 27.41328701 0.4375 29.125 C0.31181641 30.49011719 0.31181641 30.49011719 0.18359375 31.8828125 C0.12300781 32.58148438 0.06242187 33.28015625 0 34 C-1.9375 34.5625 -1.9375 34.5625 -4 35 C-5.70089219 33.29910781 -5.32747264 31.01353847 -5.5 28.6875 C-5.79652708 24.68701855 -5.79652708 24.68701855 -6.59375 20.76953125 C-7 19 -7 19 -6 17 C-5.80199313 13.8025557 -5.65410911 10.61238393 -5.5703125 7.41015625 C-5.4765625 5.40625 -5.4765625 5.40625 -5 2 C-2 0 -2 0 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(60,24)\"><\/path><\/svg>\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tEducation\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\"><path d=\"M0 0 C3.63 0 7.26 0 11 0 C11.02699468 3.08339204 11.0468366 6.16654719 11.0625 9.25 C11.07087891 10.12269531 11.07925781 10.99539063 11.08789062 11.89453125 C11.09272461 13.16103516 11.09272461 13.16103516 11.09765625 14.453125 C11.10551147 15.61569824 11.10551147 15.61569824 11.11352539 16.80175781 C11.00036998 18.99283598 10.60552448 20.89637861 10 23 C12.37305578 23.41780879 12.37305578 23.41780879 15 23 C15.433125 22.21625 15.86625 21.4325 16.3125 20.625 C18.2572023 17.59990754 18.84072324 17.49190073 22.1875 16.6875 C23.445625 16.460625 24.70375 16.23375 26 16 C26.144375 15.38125 26.28875 14.7625 26.4375 14.125 C27 12 27 12 28 10 C26.35 10 24.7 10 23 10 C23.33 8.02 23.66 6.04 24 4 C25.65 4 27.3 4 29 4 C29.33 2.68 29.66 1.36 30 0 C32.97 0 35.94 0 39 0 C39.495 1.485 39.495 1.485 40 3 C40.825 3.28875 41.65 3.5775 42.5 3.875 C43.325 4.24625 44.15 4.6175 45 5 C45.8125 7.625 45.8125 7.625 46 10 C44.35 10 42.7 10 41 10 C41.66 11.98 42.32 13.96 43 16 C42.34 16 41.68 16 41 16 C41.34224609 16.85271484 41.34224609 16.85271484 41.69140625 17.72265625 C43.66411246 23.02153974 44.29178872 26.4805391 43 32 C43.66 32 44.32 32 45 32 C44.98839844 32.61488281 44.97679687 33.22976562 44.96484375 33.86328125 C44.95582031 34.67152344 44.94679687 35.47976562 44.9375 36.3125 C44.92589844 37.11300781 44.91429687 37.91351563 44.90234375 38.73828125 C44.90342145 41.16861334 44.90342145 41.16861334 46 44 C46.495 48.95 46.495 48.95 47 54 C25.88 54 4.76 54 -17 54 C-16.67 52.35 -16.34 50.7 -16 49 C-15.01 49 -14.02 49 -13 49 C-13 49.66 -13 50.32 -13 51 C-12.01 51 -11.02 51 -10 51 C-10 47.37 -10 43.74 -10 40 C-10.99 40 -11.98 40 -13 40 C-13 42.31 -13 44.62 -13 47 C-13.99 47 -14.98 47 -16 47 C-16 43.7 -16 40.4 -16 37 C-14.02 37 -12.04 37 -10 37 C-10.01160156 36.07316406 -10.02320313 35.14632812 -10.03515625 34.19140625 C-10.04417969 32.99386719 -10.05320312 31.79632813 -10.0625 30.5625 C-10.07410156 29.36753906 -10.08570313 28.17257813 -10.09765625 26.94140625 C-10 24 -10 24 -9 23 C-7.33382885 22.95936168 -5.66611905 22.957279 -4 23 C-4 23.99 -4 24.98 -4 26 C-4.99 26 -5.98 26 -7 26 C-7 34.25 -7 42.5 -7 51 C-6.01 51 -5.02 51 -4 51 C-4.061875 49.88625 -4.12375 48.7725 -4.1875 47.625 C-4.125625 46.42875 -4.06375 45.2325 -4 44 C-0.18977687 41.45985125 2.53470816 41.41393045 7 42 C9 43.125 9 43.125 10 45 C10.1875 48.1875 10.1875 48.1875 10 51 C10.99 51 11.98 51 13 51 C13 42.75 13 34.5 13 26 C7.72 26 2.44 26 -3 26 C-3 25.01 -3 24.02 -3 23 C-1.68 23 -0.36 23 1 23 C0.7525 21.205625 0.7525 21.205625 0.5 19.375 C-0.23219971 12.92958003 -0.08292095 6.47704735 0 0 Z M4 3 C4 3.99 4 4.98 4 6 C4.99 6 5.98 6 7 6 C7 5.01 7 4.02 7 3 C6.01 3 5.02 3 4 3 Z M32 3 C32 3.33 32 3.66 32 4 C33.65 4 35.3 4 37 4 C37 3.67 37 3.34 37 3 C35.35 3 33.7 3 32 3 Z M40 7 C40.33 7.99 40.66 8.98 41 10 C41.33 9.01 41.66 8.02 42 7 C41.34 7 40.68 7 40 7 Z M4 9 C4 9.66 4 10.32 4 11 C4.99 11 5.98 11 7 11 C7 10.34 7 9.68 7 9 C6.01 9 5.02 9 4 9 Z M33 11 C32.34 12.32 31.68 13.64 31 15 C32.98 15.99 32.98 15.99 35 17 C35.99 16.34 36.98 15.68 38 15 C38 14.34 38 13.68 38 13 C35.525 12.01 35.525 12.01 33 11 Z M4 14 C4 14.99 4 15.98 4 17 C4.99 17 5.98 17 7 17 C7 16.01 7 15.02 7 14 C6.01 14 5.02 14 4 14 Z M38 18 C39 20 39 20 39 20 Z M4 19 C4 20.32 4 21.64 4 23 C4.99 23 5.98 23 7 23 C7 21.68 7 20.36 7 19 C6.01 19 5.02 19 4 19 Z M19 22 C18.75787127 23.98128508 18.75787127 23.98128508 18.875 26.125 C18.936875 28.043125 18.936875 28.043125 19 30 C19.99 30 20.98 30 22 30 C22 32.31 22 34.62 22 37 C21.01 37 20.02 37 19 37 C19 35.35 19 33.7 19 32 C18.01 32 17.02 32 16 32 C16 38.27 16 44.54 16 51 C16.99 51 17.98 51 19 51 C19 46.71 19 42.42 19 38 C19.99 38 20.98 38 22 38 C22 42.29 22 46.58 22 51 C22.33 51 22.66 51 23 51 C23.59055954 46.32712595 24.17436068 41.65349747 24.75195312 36.97900391 C24.95699946 35.34307321 25.17243677 33.70844858 25.390625 32.07421875 C25.85828638 28.41292243 26.04103798 25.53796366 25 22 C25.66 22 26.32 22 27 22 C27 21.34 27 20.68 27 20 C22.50695418 19.57496554 22.50695418 19.57496554 19 22 Z M30 23 C30 23.66 30 24.32 30 25 C32.475 25.99 32.475 25.99 35 27 C36.32 25.68 37.64 24.36 39 23 C34.98990901 20.32660601 34.01009099 20.32660601 30 23 Z M38 28 C38.66 28.66 39.32 29.32 40 30 C40 29.34 40 28.68 40 28 C39.34 28 38.68 28 38 28 Z M34 30 C31.12608179 31.17274994 31.12608179 31.17274994 29 33 C30.69495956 34.66846734 30.69495956 34.66846734 33 36 C36.37036311 35.75925978 37.58798021 35.41201979 40 33 C37.30128645 31.1915405 37.30128645 31.1915405 34 30 Z M28 37 C27.67 37.66 27.34 38.32 27 39 C27.99 38.67 28.98 38.34 30 38 C29.34 37.67 28.68 37.34 28 37 Z M39 37 C39 37.66 39 38.32 39 39 C39.66 39 40.32 39 41 39 C41 38.34 41 37.68 41 37 C40.34 37 39.68 37 39 37 Z M29.625 41.4375 C29.08875 41.953125 28.5525 42.46875 28 43 C31.38943198 44.8386571 31.38943198 44.8386571 35 46 C38.4030585 44.84237864 38.4030585 44.84237864 41 43 C37.12472171 40.41648114 33.84837727 38.88124534 29.625 41.4375 Z M-1 46 C-1.04063832 47.66617115 -1.042721 49.33388095 -1 51 C1.64 51 4.28 51 7 51 C7.042721 49.33388095 7.04063832 47.66617115 7 46 C5.88163776 44.65595225 5.88163776 44.65595225 3 44.875 C0.11836224 44.65595225 0.11836224 44.65595225 -1 46 Z M26 46 C26.33 47.32 26.66 48.64 27 50 C28.32 49.01 29.64 48.02 31 47 C29.35 46.67 27.7 46.34 26 46 Z M40 46 C39.34 46.66 38.68 47.32 38 48 C40.475 48.99 40.475 48.99 43 50 C42.67 48.68 42.34 47.36 42 46 C41.34 46 40.68 46 40 46 Z M34 49 C33.34 49.66 32.68 50.32 32 51 C33.65 51 35.3 51 37 51 C36.01 50.34 35.02 49.68 34 49 Z \" fill=\"#FFFFFF\" transform=\"translate(17,5)\"><\/path><path d=\"M0 0 C-0.75 6.75 -0.75 6.75 -3 9 C-3.99 9 -4.98 9 -6 9 C-6.36521739 3.52173913 -6.36521739 3.52173913 -4.6875 1.125 C-3 0 -3 0 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(23,32)\"><\/path><\/svg>\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tElectrical and Energy\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\"><path d=\"M0 0 C4.86281844 4.21444265 8.69457052 8.29478995 9.23828125 14.890625 C9.39316641 21.90121651 9.42601512 26.4391092 5 32 C-0.22669182 37.21481297 -3.78403188 39.14579975 -11.3125 39.25 C-18.03516645 39.18284795 -21.61858506 38.10450622 -26.6875 33.625 C-30.86994998 28.87735408 -32.69098257 25.09017434 -33.3125 18.875 C-32.81213304 12.67044967 -31.00470839 6.36252316 -26.25 2.0625 C-17.65591306 -3.39143979 -9.30694725 -4.93758044 0 0 Z M-13 6 C-13.28875 6.78375 -13.5775 7.5675 -13.875 8.375 C-15 11 -15 11 -17 13 C-17.14768913 15.51749828 -17.14768913 15.51749828 -16 18 C-13.03292954 19.85916824 -13.03292954 19.85916824 -10 21 C-10 21.66 -10 22.32 -10 23 C-11.98 23 -13.96 23 -16 23 C-15.5359375 23.86625 -15.5359375 23.86625 -15.0625 24.75 C-14.07416636 26.84294184 -13.4831387 28.74535275 -13 31 C-12.01 31 -11.02 31 -10 31 C-9.690625 30.195625 -9.38125 29.39125 -9.0625 28.5625 C-8 26 -8 26 -7 25 C-6.95919217 23.00041636 -6.95745644 20.99954746 -7 19 C-8.98 18.01 -10.96 17.02 -13 16 C-13 15.01 -13 14.02 -13 13 C-10.03 13.495 -10.03 13.495 -7 14 C-7.309375 13.4225 -7.61875 12.845 -7.9375 12.25 C-8.92583364 10.15705816 -9.5168613 8.25464725 -10 6 C-10.99 6 -11.98 6 -13 6 Z \" fill=\"#FFFFFF\" transform=\"translate(55,25)\"><\/path><path d=\"M0 0 C1.13985352 -0.0299707 1.13985352 -0.0299707 2.30273438 -0.06054688 C9.2585454 -0.05460681 14.46393562 2.09245409 19.625 6.75 C21.0625 9.4375 21.0625 9.4375 21.1875 12.9375 C19.84061721 17.12780203 17.88709009 19.40330567 14.0625 21.4375 C4.16514058 24.82375142 -6.33746543 24.83751482 -15.984375 20.703125 C-18.2893228 19.20951883 -19.50979655 17.77734733 -20.9375 15.4375 C-21.4375 12 -21.4375 12 -20.9375 8.4375 C-15.53614197 1.23568929 -8.44581843 -0.0784 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(20.9375,-0.4375)\"><\/path><path d=\"M0 0 C0.52464844 0.33773438 1.04929688 0.67546875 1.58984375 1.0234375 C9.71382914 5.70047401 17.83891313 6.28794336 27 7 C25.7038361 10.05621803 24.32165269 12.60547032 22 15 C16.0019965 16.79731115 10.35839947 14.74871554 4.91015625 12.16796875 C2.88494164 10.92964734 1.45570972 9.88066846 0 8 C-0.39078556 5.27492202 -0.13616953 2.76878044 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(0,19)\"><\/path><path d=\"M0 0 C0.7734375 0.34933594 1.546875 0.69867188 2.34375 1.05859375 C8.32178877 3.67028643 13.47271928 5.62342611 20 6 C20.99 8.97 21.98 11.94 23 15 C15.21569061 15.43246163 8.31307515 14.38541411 1.875 9.75 C-0.48366457 6.2906253 -0.40222929 4.10273875 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(0,42)\"><\/path><path d=\"M0 0 C0.99 0.4021875 0.99 0.4021875 2 0.8125 C2.99 1.204375 3.98 1.59625 5 2 C5.92425781 2.37898438 5.92425781 2.37898438 6.8671875 2.765625 C11.27712589 4.51587292 15.27918074 5.50824799 20 6 C20 8.97 20 11.94 20 15 C11.66691456 13.97521927 6.04065086 13.04065086 0 7 C-0.125 3.375 -0.125 3.375 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(0,31)\"><\/path><\/svg>\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tFinance\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\"><path d=\"M0 0 C1.66227542 0.60390026 3.32636057 1.20284157 4.9921875 1.796875 C6.62193732 2.44252669 8.24956051 3.09357251 9.875 3.75 C10.70257813 4.059375 11.53015625 4.36875 12.3828125 4.6875 C16.47086321 6.34909481 19.24243735 7.69073291 21.5546875 11.55078125 C23.01507026 15.03596497 23.36393014 17.26971604 23 21 C22.34 21 21.68 21 21 21 C21.11795925 25.68157901 21.24218549 30.36293288 21.37231445 35.04418945 C21.41572146 36.637893 21.45739219 38.2316448 21.49731445 39.82543945 C21.55487807 42.11163908 21.61861149 44.39759449 21.68359375 46.68359375 C21.70030624 47.40026718 21.71701874 48.11694061 21.73423767 48.85533142 C21.55018654 52.21527382 21.55018654 52.21527382 23 55 C23.125 57.5 23.125 57.5 23 60 C21.22083533 61.77916467 18.61686701 61.12764835 16.2109375 61.12939453 C14.9729541 61.13254669 13.7349707 61.13569885 12.45947266 61.13894653 C11.09798141 61.13715675 9.73649049 61.1351058 8.375 61.1328125 C6.98876936 61.13348559 5.60253883 61.13445566 4.21630859 61.13571167 C1.30760578 61.1371884 -1.60106637 61.1350349 -4.50976562 61.13037109 C-8.24596598 61.12467381 -11.98209452 61.12795294 -15.71829224 61.13394356 C-18.58179266 61.13754985 -21.44527593 61.13641027 -24.30877686 61.13381577 C-25.68674732 61.13314668 -27.06471932 61.13397426 -28.44268799 61.13629532 C-30.36543754 61.13882292 -32.28819252 61.13429024 -34.2109375 61.12939453 C-35.85521729 61.12820114 -35.85521729 61.12820114 -37.53271484 61.12698364 C-40 61 -40 61 -41 60 C-41.125 57.5 -41.125 57.5 -41 55 C-40.505 54.505 -40.505 54.505 -40 54 C-39.84213692 52.14825294 -39.74892644 50.2909089 -39.68359375 48.43359375 C-39.62075195 46.7465332 -39.62075195 46.7465332 -39.55664062 45.02539062 C-39.51732422 43.84138672 -39.47800781 42.65738281 -39.4375 41.4375 C-39.39431641 40.24962891 -39.35113281 39.06175781 -39.30664062 37.83789062 C-39.20016454 34.89205216 -39.09815159 31.9461257 -39 29 C-38.01 28.67 -37.02 28.34 -36 28 C-36 35.59 -36 43.18 -36 51 C-35.01 51 -34.02 51 -33 51 C-33 42.75 -33 34.5 -33 26 C-34.65 26 -36.3 26 -38 26 C-38.33 24.35 -38.66 22.7 -39 21 C-39.66 21 -40.32 21 -41 21 C-41.41467461 16.74958524 -40.91743716 13.52263343 -38.69921875 9.82543945 C-34.80850346 5.64571557 -29.07587047 3.93760535 -23.875 1.875 C-22.6890625 1.35679687 -21.503125 0.83859375 -20.28125 0.3046875 C-12.35699427 -2.91399474 -7.77468181 -3.53248325 0 0 Z M-22 4.75 C-23.67835937 5.41515625 -23.67835937 5.41515625 -25.390625 6.09375 C-26.45796875 6.53203125 -27.5253125 6.9703125 -28.625 7.421875 C-29.60726563 7.81987305 -30.58953125 8.21787109 -31.6015625 8.62792969 C-34.25590361 10.14639437 -34.97710639 11.16748727 -36 14 C-33.69 14 -31.38 14 -29 14 C-28.67 13.01 -28.34 12.02 -28 11 C-19.42 10.67 -10.84 10.34 -2 10 C-2 10.99 -2 11.98 -2 13 C-9.92 13 -17.84 13 -26 13 C-26 17.62 -26 22.24 -26 27 C-14.78 27 -3.56 27 8 27 C8 22.38 8 17.76 8 13 C5.36 13 2.72 13 0 13 C0 12.01 0 11.02 0 10 C3.3 10.33 6.6 10.66 10 11 C10.495 12.485 10.495 12.485 11 14 C13.31 14 15.62 14 18 14 C16.97710639 11.16748727 16.25590361 10.14639437 13.6015625 8.62792969 C12.61929688 8.22993164 11.63703125 7.83193359 10.625 7.421875 C9.02398437 6.76445312 9.02398437 6.76445312 7.390625 6.09375 C6.27171875 5.6503125 5.1528125 5.206875 4 4.75 C2.88109375 4.29109375 1.7621875 3.8321875 0.609375 3.359375 C-9.13259468 -0.59388806 -12.32519599 0.78199282 -22 4.75 Z M-39 17 C-39 17.66 -39 18.32 -39 19 C-35.7 19 -32.4 19 -29 19 C-29 18.34 -29 17.68 -29 17 C-32.3 17 -35.6 17 -39 17 Z M11 17 C11 17.66 11 18.32 11 19 C14.3 19 17.6 19 21 19 C21 18.34 21 17.68 21 17 C17.7 17 14.4 17 11 17 Z M-36 21 C-36 21.66 -36 22.32 -36 23 C-33.69 23 -31.38 23 -29 23 C-29 22.34 -29 21.68 -29 21 C-31.31 21 -33.62 21 -36 21 Z M11 21 C11 21.66 11 22.32 11 23 C13.31 23 15.62 23 18 23 C18 22.34 18 21.68 18 21 C15.69 21 13.38 21 11 21 Z M-30 26 C-30 34.25 -30 42.5 -30 51 C-27.36 51 -24.72 51 -22 51 C-22 44.07 -22 37.14 -22 30 C-24.97 29.505 -24.97 29.505 -28 29 C-28.66 28.01 -29.32 27.02 -30 26 Z M15 26 C15 34.25 15 42.5 15 51 C15.99 51 16.98 51 18 51 C18 42.75 18 34.5 18 26 C17.01 26 16.02 26 15 26 Z M-19 30 C-19 36.93 -19 43.86 -19 51 C-18.01 51 -17.02 51 -16 51 C-16 44.07 -16 37.14 -16 30 C-16.99 30 -17.98 30 -19 30 Z M-13 30 C-13 31.98 -13 33.96 -13 36 C-12.05125 35.814375 -11.1025 35.62875 -10.125 35.4375 C-7 35 -7 35 -5 36 C-5 34.02 -5 32.04 -5 30 C-7.64 30 -10.28 30 -13 30 Z M-2 30 C-2 36.93 -2 43.86 -2 51 C-1.01 51 -0.02 51 1 51 C1 44.07 1 37.14 1 30 C0.01 30 -0.98 30 -2 30 Z M11 26 C10.67 26.99 10.34 27.98 10 29 C8.02 29.33 6.04 29.66 4 30 C4 36.93 4 43.86 4 51 C6.64 51 9.28 51 12 51 C12 42.75 12 34.5 12 26 C11.67 26 11.34 26 11 26 Z M-11.61328125 38.14453125 C-13.53906265 40.721281 -13.29961289 42.51096821 -13.1875 45.6875 C-13.16042969 46.68136719 -13.13335938 47.67523438 -13.10546875 48.69921875 C-13.07066406 49.45847656 -13.03585938 50.21773437 -13 51 C-12.01 51 -11.02 51 -10 51 C-10 47.37 -10 43.74 -10 40 C-9.34 40 -8.68 40 -8 40 C-8 43.63 -8 47.26 -8 51 C-7.01 51 -6.02 51 -5 51 C-4.91885894 49.22992286 -4.86074495 47.45877902 -4.8125 45.6875 C-4.77769531 44.70136719 -4.74289063 43.71523438 -4.70703125 42.69921875 C-4.77076227 39.97865275 -4.77076227 39.97865275 -6.38671875 38.14453125 C-8.58593773 36.58431052 -9.41406227 36.58431052 -11.61328125 38.14453125 Z M-36 53 C-36 53.33 -36 53.66 -36 54 C-21.81 54 -7.62 54 7 54 C7 54.99 7 55.98 7 57 C-8.18 57 -23.36 57 -39 57 C-39 57.33 -39 57.66 -39 58 C-19.2 58 0.6 58 21 58 C21 57.67 21 57.34 21 57 C17.04 57 13.08 57 9 57 C9 56.01 9 55.02 9 54 C11.97 54 14.94 54 18 54 C18 53.67 18 53.34 18 53 C0.18 53 -17.64 53 -36 53 Z \" fill=\"#FFFFFF\" transform=\"translate(41,3)\"><\/path><path d=\"M0 0 C0.33 0.33 0.66 0.66 1 1 C1.33 0.34 1.66 -0.32 2 -1 C2.99 -0.67 3.98 -0.34 5 0 C5.33 0.99 5.66 1.98 6 3 C6.66 1.68 7.32 0.36 8 -1 C8.99 -0.67 9.98 -0.34 11 0 C10.01 3.3 9.02 6.6 8 10 C6.68 10 5.36 10 4 10 C3.67 9.01 3.34 8.02 3 7 C2.278125 7.680625 1.55625 8.36125 0.8125 9.0625 C-2 11 -2 11 -4.6875 10.875 C-7 10 -7 10 -9 8 C-9.375 5.0625 -9.375 5.0625 -9 2 C-6.11353359 -1.31409106 -4.06037509 -1.31687841 0 0 Z M-5 2 C-5.33 3.65 -5.66 5.3 -6 7 C-4.68 7 -3.36 7 -2 7 C-2 5.68 -2 4.36 -2 3 C-2.99 2.67 -3.98 2.34 -5 2 Z \" fill=\"#FFFFFF\" transform=\"translate(37,18)\"><\/path><path d=\"M0 0 C0 0.99 0 1.98 0 3 C-1.65 3 -3.3 3 -5 3 C-5 4.32 -5 5.64 -5 7 C-4.67 6.67 -4.34 6.34 -4 6 C-4 5.34 -4 4.68 -4 4 C-2.35 4 -0.7 4 1 4 C0.67 5.98 0.34 7.96 0 10 C-2.8125 10.625 -2.8125 10.625 -6 11 C-9 9 -9 9 -9.8125 6.625 C-10.02443247 3.65794547 -9.71818252 2.40545553 -8 0 C-4.71023192 -1.09658936 -3.28696233 -0.79953138 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(26,18)\"><\/path><path d=\"M0 0 C0.99 0 1.98 0 3 0 C2.42655063 2.86724686 2.1385485 3.8614515 0 6 C-0.99 6 -1.98 6 -3 6 C-2.42655063 3.13275314 -2.1385485 2.1385485 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(32,6)\"><\/path><path d=\"M0 0 C0.99 0 1.98 0 3 0 C3 1.65 3 3.3 3 5 C2.01 5 1.02 5 0 5 C0 3.35 0 1.7 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(14,34)\"><\/path><path d=\"M0 0 C0.99 0 1.98 0 3 0 C3 1.65 3 3.3 3 5 C2.01 4.67 1.02 4.34 0 4 C0 2.68 0 1.36 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(47,47)\"><\/path><path d=\"M0 0 C0.99 0 1.98 0 3 0 C2.67 1.65 2.34 3.3 2 5 C1.34 5 0.68 5 0 5 C0 3.35 0 1.7 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(14,47)\"><\/path><path d=\"M0 0 C0.66 0 1.32 0 2 0 C2 1.65 2 3.3 2 5 C1.01 5 0.02 5 -1 5 C-0.67 3.35 -0.34 1.7 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(48,40)\"><\/path><path d=\"M0 0 C0.99 0.33 1.98 0.66 3 1 C3 2.32 3 3.64 3 5 C2.01 5 1.02 5 0 5 C0 3.35 0 1.7 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(14,40)\"><\/path><path d=\"M0 0 C0.66 0 1.32 0 2 0 C2 1.65 2 3.3 2 5 C1.01 4.67 0.02 4.34 -1 4 C-0.67 2.68 -0.34 1.36 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(48,34)\"><\/path><\/svg>\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tGovernment\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\"><path d=\"M0 0 C3.1875 1.5 3.1875 1.5 5 3 C5.61875 2.505 6.2375 2.01 6.875 1.5 C11.29155566 -0.61994672 15.18397319 -0.82450379 20 0 C23.48691814 1.732763 25.52919529 4.12259122 27.375 7.5625 C28 10 28 10 28 14 C29.98 14 31.96 14 34 14 C34 14.99 34 15.98 34 17 C31.69 17 29.38 17 27 17 C26.92724854 17.72469482 26.85449707 18.44938965 26.77954102 19.19604492 C25.78251758 22.78226922 24.18324006 24.27419994 21.52734375 26.86328125 C20.62822266 27.74951172 19.72910156 28.63574219 18.80273438 29.54882812 C17.85720703 30.46083984 16.91167969 31.37285156 15.9375 32.3125 C14.97760179 33.25232276 14.01860671 34.19306889 13.06054688 35.13476562 C10.71576088 37.43242024 8.36215473 39.7202276 6 42 C3.13369265 40.60556009 0.71476763 39.15790664 -1.75 37.125 C-2.36359375 36.63257813 -2.9771875 36.14015625 -3.609375 35.6328125 C-5 34 -5 34 -5 30 C-0.62140745 30.50522222 1.81651224 33.17827222 5 36 C15.14785334 27.97281132 15.14785334 27.97281132 23 18 C22.34 18 21.68 18 21 18 C19.36323743 19.9600281 19.36323743 19.9600281 18 22 C16.35 21.67 14.7 21.34 13 21 C12.34 21.99 11.68 22.98 11 24 C8 23 8 23 6.3125 19.9375 C5.879375 18.968125 5.44625 17.99875 5 17 C3.35 19.31 1.7 21.62 0 24 C-0.99 23.67 -1.98 23.34 -3 23 C-3.33 22.34 -3.66 21.68 -4 21 C-4.721875 21.268125 -5.44375 21.53625 -6.1875 21.8125 C-9 22 -9 22 -11.8125 19.5625 C-12.534375 18.716875 -13.25625 17.87125 -14 17 C-13.34 17.928125 -12.68 18.85625 -12 19.8125 C-10 23 -10 23 -10 26 C-11.75 25.875 -11.75 25.875 -14 25 C-18 19.77777778 -18 19.77777778 -18 17 C-20.31 17 -22.62 17 -25 17 C-25 16.01 -25 15.02 -25 14 C-22.69 14 -20.38 14 -18 14 C-18.0825 13.13375 -18.165 12.2675 -18.25 11.375 C-17.93918637 7.17901595 -16.59375096 5.26071549 -14 2 C-9.55299615 -0.96466923 -5.21871437 -0.52568072 0 0 Z M-14 8 C-14.96298724 11.17562802 -14.96298724 11.17562802 -15 14 C-13.576875 14.185625 -13.576875 14.185625 -12.125 14.375 C-9 15 -9 15 -7 17 C-5.35 16.01 -3.7 15.02 -2 14 C-1.67 14.99 -1.34 15.98 -1 17 C1.50037734 14.82575883 2.43628586 13.26954202 3 10 C6 11 6 11 7.6875 14.0625 C8.120625 15.031875 8.55375 16.00125 9 17 C9.66 17 10.32 17 11 17 C11.33 16.34 11.66 15.68 12 15 C12.99 14.67 13.98 14.34 15 14 C15.33 14.99 15.66 15.98 16 17 C16.66 16.67 17.32 16.34 18 16 C18 15.34 18 14.68 18 14 C19.98 14 21.96 14 24 14 C23.76435605 9.91550495 23.59037881 7.65785068 20.8125 4.5625 C17.43388366 2.68549092 15.81030177 2.37790992 12 3 C9.99384866 4.32405988 7.99330842 5.65668346 6 7 C3.20372964 6.91526453 1.9290542 5.95452192 -0.4375 4.4375 C-6.34444855 1.12384593 -9.53807588 3.33526115 -14 8 Z \" fill=\"#FFF6F6\" transform=\"translate(30,0)\"><\/path><path d=\"M0 0 C2.66015625 1.0390625 2.66015625 1.0390625 5.1875 2.25 C8.59517212 3.86262589 8.59517212 3.86262589 12.19140625 3.375 C13.54336542 2.63616842 14.87468776 1.85798946 16.1796875 1.0390625 C18.84810898 -0.48411371 21.01082161 -0.42702548 24 0 C26 2 26 2 26.58203125 4.765625 C25.8201654 8.99934934 24.22127462 9.9361971 20.81445312 12.33984375 C20.11255859 12.80519531 19.41066406 13.27054688 18.6875 13.75 C17.99720703 14.23082031 17.30691406 14.71164063 16.59570312 15.20703125 C14.74333562 16.49205528 12.87748755 17.75207793 11 19 C10.01 19.66 9.02 20.32 8 21 C-0.27797843 22.39863683 -8.22181129 19.51053929 -16 17 C-16.33 17.99 -16.66 18.98 -17 20 C-18.64574566 20.02688151 -20.29161413 20.04634123 -21.9375 20.0625 C-22.85402344 20.07410156 -23.77054688 20.08570312 -24.71484375 20.09765625 C-27 20 -27 20 -28 19 C-28.09986975 16.15664952 -28.13877881 13.34302837 -28.125 10.5 C-28.12886719 9.70207031 -28.13273437 8.90414062 -28.13671875 8.08203125 C-28.12660767 2.12660767 -28.12660767 2.12660767 -27 1 C-25.35659133 0.90145345 -23.7088539 0.87027589 -22.0625 0.875 C-21.16660156 0.87242188 -20.27070313 0.86984375 -19.34765625 0.8671875 C-17 1 -17 1 -15 2 C-14.10667969 1.54753906 -14.10667969 1.54753906 -13.1953125 1.0859375 C-9.05681068 -0.96122176 -4.49923401 -0.53775705 0 0 Z M-16 6 C-16 8.64 -16 11.28 -16 14 C-13.8131784 14.48225331 -11.62550745 14.96065583 -9.4375 15.4375 C-8.21933594 15.70433594 -7.00117188 15.97117187 -5.74609375 16.24609375 C-4.50988281 16.49488281 -3.27367187 16.74367188 -2 17 C-0.80503906 17.26039062 0.38992187 17.52078125 1.62109375 17.7890625 C5.70765999 18.04417762 7.1706793 17.24354419 10.5 14.9375 C11.43457031 14.29554687 12.36914062 13.65359375 13.33203125 12.9921875 C16.71103885 10.46906323 19.88280995 7.84010649 23 5 C22.34 4.34 21.68 3.68 21 3 C18.85299207 4.14367738 16.70737007 5.28982607 14.5625 6.4375 C13.95083984 6.76298828 13.33917969 7.08847656 12.70898438 7.42382812 C9.66283794 8.93715142 9.66283794 8.93715142 7 11 C2.52519101 11.17548271 -1.60833973 10.85690932 -6 10 C-6 9.01 -6 8.02 -6 7 C-2.37 7.66 1.26 8.32 5 9 C4.67 7.68 4.34 6.36 4 5 C-4.17579188 2.43504568 -8.22252005 2.83627934 -16 6 Z M-25 4 C-25 8.29 -25 12.58 -25 17 C-23.02 17 -21.04 17 -19 17 C-19 12.71 -19 8.42 -19 4 C-20.98 4 -22.96 4 -25 4 Z \" fill=\"#FFF6F6\" transform=\"translate(28,43)\"><\/path><path d=\"M0 0 C0.99 0 1.98 0 3 0 C3 1.32 3 2.64 3 4 C2.01 4 1.02 4 0 4 C0 2.68 0 1.36 0 0 Z \" fill=\"#FFF8F8\" transform=\"translate(21,26)\"><\/path><\/svg>\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tHealth and Wellness\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\"><path d=\"M0 0 C3.3125 2 3.3125 2 6 4 C9.12498166 4.3373846 9.12498166 4.3373846 11.1875 2 C14.25850931 -0.18382884 16.24744367 -0.59264959 20.00390625 -0.38671875 C23.38042876 0.26744119 25.45175467 1.75511721 28 4 C30.31691163 7.62647038 30.28119746 10.93390961 29.59375 15.06640625 C28.54368417 18.48602854 26.88527768 19.97416673 24 22 C19.78356434 23.39680276 16.87899705 23.35497958 12.75 21.6875 C11.8425 21.130625 10.935 20.57375 10 20 C9.21625 19.608125 8.4325 19.21625 7.625 18.8125 C7.08875 18.544375 6.5525 18.27625 6 18 C5.21625 18.639375 4.4325 19.27875 3.625 19.9375 C-0.17367482 22.92217308 -2.15772359 23.4656035 -7 23 C-10.6578218 20.96006092 -12.66946174 19.49580738 -15 16 C-15.68343706 12.22311096 -15.85107095 8.52813111 -13.94921875 5.11328125 C-9.88394255 0.16059963 -6.27613615 -0.89993014 0 0 Z M-11.875 6.75 C-13.59594712 10.19189423 -13.03958743 12.361444 -12 16 C-9.50308805 18.78227332 -7.80714078 19.80269892 -4.1875 20.6875 C1.48585394 19.46383542 5.02126488 14.95981796 9.04296875 10.9765625 C14.16601722 6.12106202 14.16601722 6.12106202 18.875 5.4375 C22 6 22 6 24 8 C24.33015665 11.10347254 24.50531294 13.15781176 22.875 15.875 C20.06181421 17.56291147 18.22507435 17.45151041 15 17 C12.125 15 12.125 15 10 13 C9.65699357 16.13728919 9.65699357 16.13728919 12.0625 18.1875 C15.73396914 20.45287458 17.75368609 20.61764566 22 20 C25.30748965 17.38882396 26.81680509 15.37396185 27.375 11.1875 C27.25902016 7.83246151 27.25902016 7.83246151 24.8125 5.1875 C21.94061626 2.95381265 20.61181438 2 17 2 C12.70859144 4.14206132 9.59198828 7.19826939 6.3125 10.625 C0.29073187 16.8626881 0.29073187 16.8626881 -3.9375 17.3125 C-7 17 -7 17 -8.9375 15.375 C-10.35168205 12.21388719 -9.87877792 10.29541719 -9 7 C-8 6 -8 6 -4.125 5.75 C-0.27815315 5.77747748 -0.27815315 5.77747748 1.875 7.5 C2.24625 7.995 2.6175 8.49 3 9 C3.66 9 4.32 9 5 9 C3.89184175 5.78634109 3.01470446 5.0085776 0 3.25 C-5.22659822 1.07225074 -7.86992986 3.01193453 -11.875 6.75 Z M-8 9 C-7.81171228 11.44480079 -7.81171228 11.44480079 -7 14 C-5.03241727 15.36020151 -5.03241727 15.36020151 -3 16 C-1.35 14.35 0.3 12.7 2 11 C0.18777466 8.9375006 0.18777466 8.9375006 -2 7 C-5.18490007 6.7226499 -5.18490007 6.7226499 -8 9 Z M13 10 C14.04874998 12.62187494 14.64931313 13.79371361 17.125 15.25 C17.74375 15.4975 18.3625 15.745 19 16 C19.99 15.34 20.98 14.68 22 14 C22.41666667 11.5 22.41666667 11.5 22 9 C21.34 8.34 20.68 7.68 20 7 C16.48283697 7 15.62878252 7.82445585 13 10 Z \" fill=\"#FFF0F0\" transform=\"translate(31,4)\"><\/path><path d=\"M0 0 C2.0625 0.9375 2.0625 0.9375 2.8515625 2.99609375 C3.16042718 7.30304008 0.93112211 9.72495035 -1.5625 13 C-2.00207031 13.61166016 -2.44164062 14.22332031 -2.89453125 14.85351562 C-7.99261979 21.76807853 -7.99261979 21.76807853 -11.9375 23.9375 C-16.03907234 24.553494 -20.10753545 24.63423628 -24.25 24.6875 C-25.37212891 24.71714844 -26.49425781 24.74679688 -27.65039062 24.77734375 C-30.41283207 24.84787417 -33.17443774 24.90065493 -35.9375 24.9375 C-35.9375 25.9275 -35.9375 26.9175 -35.9375 27.9375 C-37.25 29.76171875 -37.25 29.76171875 -38.9375 31.625 C-39.494375 32.24761719 -40.05125 32.87023438 -40.625 33.51171875 C-41.058125 33.98222656 -41.49125 34.45273437 -41.9375 34.9375 C-45.08954981 33.54402624 -47.19921773 31.91264921 -49.609375 29.4609375 C-50.27324219 28.790625 -50.93710937 28.1203125 -51.62109375 27.4296875 C-52.30300781 26.73101562 -52.98492187 26.03234375 -53.6875 25.3125 C-54.38488281 24.60609375 -55.08226562 23.8996875 -55.80078125 23.171875 C-57.51762488 21.43151297 -59.22961832 19.68665019 -60.9375 17.9375 C-59.55689854 15.08817358 -58.47015215 12.90734056 -55.9375 10.9375 C-55.195 10.834375 -54.4525 10.73125 -53.6875 10.625 C-50.07579916 9.72207479 -48.18625868 7.80110003 -45.48828125 5.3125 C-42.54129577 2.69955569 -40.34261609 2.80229385 -36.5 2.8125 C-35.53191406 2.80992188 -34.56382813 2.80734375 -33.56640625 2.8046875 C-30.9375 2.9375 -30.9375 2.9375 -27.9375 3.9375 C-24.75341307 4.16339806 -21.57596659 4.33054559 -18.38671875 4.45507812 C-14.74895799 4.64521749 -13.04135071 4.86826619 -9.9375 6.9375 C-9.49019531 6.42058594 -9.04289062 5.90367188 -8.58203125 5.37109375 C-3.58243997 -0.07622213 -3.58243997 -0.07622213 0 0 Z M-3.5234375 4.328125 C-4.11382812 4.94171875 -4.70421875 5.5553125 -5.3125 6.1875 C-5.89773437 6.79078125 -6.48296875 7.3940625 -7.0859375 8.015625 C-8.98303232 9.92999955 -8.98303232 9.92999955 -10.7109375 12.125 C-13.82159775 14.65718659 -16.22651689 14.54079692 -20.1875 14.6875 C-21.45078125 14.74421875 -22.7140625 14.8009375 -24.015625 14.859375 C-25.46195313 14.89804687 -25.46195313 14.89804687 -26.9375 14.9375 C-26.9375 14.2775 -26.9375 13.6175 -26.9375 12.9375 C-26.09445313 12.94910156 -25.25140625 12.96070313 -24.3828125 12.97265625 C-23.28710938 12.98167969 -22.19140625 12.99070312 -21.0625 13 C-19.97195312 13.01160156 -18.88140625 13.02320313 -17.7578125 13.03515625 C-14.98572454 13.13494303 -14.98572454 13.13494303 -12.9375 11.9375 C-13.4325 9.9575 -13.4325 9.9575 -13.9375 7.9375 C-15.00871094 7.87691406 -16.07992187 7.81632812 -17.18359375 7.75390625 C-18.58074391 7.66951463 -19.97787857 7.58486594 -21.375 7.5 C-22.08205078 7.46068359 -22.78910156 7.42136719 -23.51757812 7.38085938 C-28.82421875 7.05078125 -28.82421875 7.05078125 -29.9375 5.9375 C-35.07240878 5.21450484 -39.96622046 4.74097221 -44.51171875 7.5 C-46.45189785 9.22769988 -48.23606031 10.97584012 -49.9375 12.9375 C-48.52905282 16.15274305 -46.83405214 18.25933868 -44.3125 20.6875 C-43.68085937 21.30109375 -43.04921875 21.9146875 -42.3984375 22.546875 C-41.91632812 23.00578125 -41.43421875 23.4646875 -40.9375 23.9375 C-39.9475 23.6075 -38.9575 23.2775 -37.9375 22.9375 C-36.22369674 22.82357564 -34.5063325 22.75948817 -32.7890625 22.7265625 C-31.78359375 22.69820312 -30.778125 22.66984375 -29.7421875 22.640625 C-27.63038172 22.58873788 -25.51837609 22.54440874 -23.40625 22.5078125 C-16.10547203 22.43678572 -16.10547203 22.43678572 -9.9375 18.9375 C-8.02741856 16.86514742 -6.31286545 14.69298835 -4.625 12.4375 C-4.17060547 11.85613281 -3.71621094 11.27476563 -3.24804688 10.67578125 C-0.53623801 7.20555532 -0.53623801 7.20555532 0.0625 2.9375 C-2.0384163 2.71773636 -2.0384163 2.71773636 -3.5234375 4.328125 Z M-54.9375 13.9375 C-55.5975 15.2575 -56.2575 16.5775 -56.9375 17.9375 C-52.6475 22.2275 -48.3575 26.5175 -43.9375 30.9375 C-42.6175 30.2775 -41.2975 29.6175 -39.9375 28.9375 C-44.32918507 23.66747792 -48.8801379 18.58447949 -53.9375 13.9375 C-54.2675 13.9375 -54.5975 13.9375 -54.9375 13.9375 Z \" fill=\"#FFEFEF\" transform=\"translate(60.9375,25.0625)\"><\/path><\/svg>\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tHospitality\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\"><path d=\"M0 0 C7.59 0 15.18 0 23 0 C23 0.99 23 1.98 23 3 C23.78246094 2.98839844 24.56492188 2.97679687 25.37109375 2.96484375 C26.38300781 2.95582031 27.39492188 2.94679687 28.4375 2.9375 C29.44683594 2.92589844 30.45617188 2.91429687 31.49609375 2.90234375 C34 3 34 3 35 4 C35.07205511 5.68608966 35.08386068 7.37500659 35.0625 9.0625 C35.05347656 9.98160156 35.04445312 10.90070312 35.03515625 11.84765625 C35.02355469 12.55792969 35.01195312 13.26820312 35 14 C36.134375 14.103125 37.26875 14.20625 38.4375 14.3125 C41.72279422 14.71152507 44.65841209 15.46208314 47.78515625 16.54296875 C48.57929932 16.81520264 49.37344238 17.08743652 50.19165039 17.36791992 C50.78840576 17.57650635 51.38516113 17.78509277 52 18 C52.14700056 21.16616599 52.23462106 24.33143982 52.3125 27.5 C52.35439453 28.386875 52.39628906 29.27375 52.43945312 30.1875 C52.55845098 36.6609835 51.31984598 41.07234021 47 46 C43.92126931 48.49022134 41.07078064 49.90886973 37.0625 50.25 C36.381875 50.1675 35.70125 50.085 35 50 C35.144375 51.010625 35.28875 52.02125 35.4375 53.0625 C34.92236813 57.69868681 33.98717898 59.55235201 30.62109375 62.6875 C24.95476366 65.52488735 18.15992748 64.46587687 12 64 C12 63.01 12 62.02 12 61 C15.96 61 19.92 61 24 61 C24 59.02 24 57.04 24 55 C26 53 26 53 29.125 52.875 C30.07375 52.91625 31.0225 52.9575 32 53 C31.61431269 50.5555764 31.33590575 49.30576036 29.4765625 47.61328125 C28.86554687 47.18402344 28.25453125 46.75476562 27.625 46.3125 C23.26857154 42.83272449 22.36871227 39.3138241 21 34 C17.37 34 13.74 34 10 34 C10 33.01 10 32.02 10 31 C13.63 31 17.26 31 21 31 C21 27.37 21 23.74 21 20 C17.37 20 13.74 20 10 20 C10 19.01 10 18.02 10 17 C11.18078125 16.93941406 12.3615625 16.87882812 13.578125 16.81640625 C15.1354277 16.73197418 16.69271879 16.64732751 18.25 16.5625 C19.41595703 16.50352539 19.41595703 16.50352539 20.60546875 16.44335938 C21.35957031 16.40146484 22.11367188 16.35957031 22.890625 16.31640625 C23.58188477 16.27974854 24.27314453 16.24309082 24.98535156 16.20532227 C27.35620639 16.0121859 27.35620639 16.0121859 31 15 C31.33 12.03 31.66 9.06 32 6 C29.03 6 26.06 6 23 6 C22.34 7.32 21.68 8.64 21 10 C14.73 10 8.46 10 2 10 C1.34 8.68 0.68 7.36 0 6 C-2.97 6 -5.94 6 -9 6 C-9 24.15 -9 42.3 -9 61 C-4.71 61 -0.42 61 4 61 C4 61.99 4 62.98 4 64 C1.52076199 64.02685095 -0.9581884 64.04676547 -3.4375 64.0625 C-4.14455078 64.07087891 -4.85160156 64.07925781 -5.58007812 64.08789062 C-7.38693559 64.09653588 -9.19387603 64.05220011 -11 64 C-12.74299388 62.25700612 -12.12758682 59.85593748 -12.12939453 57.48632812 C-12.13254669 56.30840698 -12.13569885 55.13048584 -12.13894653 53.91687012 C-12.1369223 52.63461548 -12.13489807 51.35236084 -12.1328125 50.03125 C-12.13376923 48.72546997 -12.13472595 47.41968994 -12.13571167 46.07434082 C-12.13718833 43.30687278 -12.13503511 40.53943696 -12.13037109 37.77197266 C-12.12467381 34.21737351 -12.12795298 30.66284986 -12.13394356 27.10825348 C-12.13841747 23.72841286 -12.13528886 20.34859277 -12.1328125 16.96875 C-12.13483673 15.68649536 -12.13686096 14.40424072 -12.13894653 13.08312988 C-12.13579437 11.90520874 -12.13264221 10.7272876 -12.12939453 9.51367188 C-12.12859894 8.47078003 -12.12780334 7.42788818 -12.12698364 6.35339355 C-12 4 -12 4 -11 3 C-9.14712498 2.92773498 -7.29166122 2.9161878 -5.4375 2.9375 C-4.42558594 2.94652344 -3.41367188 2.95554688 -2.37109375 2.96484375 C-1.19740234 2.98224609 -1.19740234 2.98224609 0 3 C0 2.01 0 1.02 0 0 Z M4 3 C4 4.32 4 5.64 4 7 C8.95 7 13.9 7 19 7 C19 5.68 19 4.36 19 3 C14.05 3 9.1 3 4 3 Z M24 21 C23.72312248 28.50645718 23.71151587 35.18585979 27.6875 41.8125 C30.66037277 44.62467694 33.0496114 45.91023763 37 47 C42.27241308 45.41827608 44.86196779 42.30358703 48 38 C49.18681726 34.43954823 49.09689832 31.56191663 49.0625 27.8125 C49.05347656 26.54019531 49.04445313 25.26789062 49.03515625 23.95703125 C49.02355469 22.98121094 49.01195313 22.00539063 49 21 C39.70406079 17.45868982 33.29593921 17.45868982 24 21 Z \" fill=\"#FFFEFE\" transform=\"translate(12,0)\"><\/path><path d=\"M0 0 C0.08139142 2.39652528 0.14067009 4.79025436 0.1875 7.1875 C0.21263672 7.86103516 0.23777344 8.53457031 0.26367188 9.22851562 C0.32933376 13.71541119 -0.2677535 16.42907832 -3 20 C-6.01757067 22.51464223 -7.54477949 22.99187106 -11.5 23.0625 C-16.17595974 21.64301222 -17.27970302 20.00043674 -20 16 C-21.14077657 12.57767028 -21.09815117 9.91326783 -21.0625 6.3125 C-21.05347656 5.13300781 -21.04445312 3.95351563 -21.03515625 2.73828125 C-21.02355469 1.83464844 -21.01195312 0.93101563 -21 0 C-13.11453138 -3.16491598 -7.96046293 -3.28978315 0 0 Z M-18 3 C-17.90386242 10.56420908 -17.90386242 10.56420908 -14.75 17.25 C-12.17416497 19.23488303 -12.17416497 19.23488303 -9.375 19 C-6.88799346 17.95283935 -5.6364318 17.12736134 -4 15 C-3.03929566 12.11788698 -2.89418117 10.30149956 -2.9375 7.3125 C-2.94652344 6.50425781 -2.95554687 5.69601563 -2.96484375 4.86328125 C-2.97644531 4.24839844 -2.98804688 3.63351563 -3 3 C-8.78250849 0.35656755 -12.21768617 0.57142819 -18 3 Z \" fill=\"#FFFEFE\" transform=\"translate(59,22)\"><\/path><path d=\"M0 0 C4.62 0 9.24 0 14 0 C14 1.32 14 2.64 14 4 C9.38 4 4.76 4 0 4 C0 2.68 0 1.36 0 0 Z \" fill=\"#FFFEFE\" transform=\"translate(22,44)\"><\/path><path d=\"M0 0 C1.32 0 2.64 0 4 0 C3.61094382 2.72339328 2.93262433 4.08903214 1.25 6.3125 C-1 8 -1 8 -3.75 7.75 C-4.4925 7.5025 -5.235 7.255 -6 7 C-6.33 5.68 -6.66 4.36 -7 3 C-5.5459375 2.5359375 -5.5459375 2.5359375 -4.0625 2.0625 C-1.15934208 1.30476658 -1.15934208 1.30476658 0 0 Z \" fill=\"#FFFEFE\" transform=\"translate(15,45)\"><\/path><path d=\"M0 0 C0.99 0.33 1.98 0.66 3 1 C1.56036361 4.35915158 -0.12416589 6.71624938 -3 9 C-5.25 8.75 -5.25 8.75 -7 8 C-7.33 6.35 -7.66 4.7 -8 3 C-6.8553125 3.0928125 -6.8553125 3.0928125 -5.6875 3.1875 C-2.95474688 3.25898085 -2.95474688 3.25898085 -1.1875 1.5 C-0.795625 1.005 -0.40375 0.51 0 0 Z \" fill=\"#FFFEFE\" transform=\"translate(16,17)\"><\/path><path d=\"M0 0 C0.99 0 1.98 0 3 0 C2.52797514 4.24822374 0.03344482 6.19989709 -3 9 C-4.9375 8.25 -4.9375 8.25 -7 7 C-7.75 4.875 -7.75 4.875 -8 3 C-6.8553125 3.0928125 -6.8553125 3.0928125 -5.6875 3.1875 C-2.49347163 2.96466081 -2.0779007 2.26680076 0 0 Z \" fill=\"#FFFEFE\" transform=\"translate(16,31)\"><\/path><path d=\"M0 0 C0.99 0 1.98 0 3 0 C2.46104623 3.7726764 1.00464642 5.68212991 -2 8 C-5.01811422 7.82246387 -5.83735215 7.16264785 -8 5 C-8 4.01 -8 3.02 -8 2 C-6.8553125 2.3403125 -6.8553125 2.3403125 -5.6875 2.6875 C-4.800625 2.790625 -3.91375 2.89375 -3 3 C-1.35405861 1.60411246 -1.35405861 1.60411246 0 0 Z \" fill=\"#FFFEFE\" transform=\"translate(51,28)\"><\/path><path d=\"M0 0 C3.96 0 7.92 0 12 0 C12 0.99 12 1.98 12 3 C8.04 3 4.08 3 0 3 C0 2.01 0 1.02 0 0 Z \" fill=\"#FFFEFE\" transform=\"translate(22,50)\"><\/path><path d=\"M0 0 C2.97 0 5.94 0 9 0 C8.67 1.32 8.34 2.64 8 4 C5.69 4 3.38 4 1 4 C0.67 2.68 0.34 1.36 0 0 Z \" fill=\"#FFFEFE\" transform=\"translate(22,36)\"><\/path><path d=\"M0 0 C2.31 0 4.62 0 7 0 C7 1.32 7 2.64 7 4 C4.36 4 1.72 4 -1 4 C-0.67 2.68 -0.34 1.36 0 0 Z \" fill=\"#FFFEFE\" transform=\"translate(23,22)\"><\/path><path d=\"M0 0 C1.32 0.33 2.64 0.66 4 1 C3.67 1.66 3.34 2.32 3 3 C2.01 3 1.02 3 0 3 C0 2.01 0 1.02 0 0 Z \" fill=\"#FFFEFE\" transform=\"translate(18,61)\"><\/path><\/svg>\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tInsurance\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\"><path d=\"M0 0 C3.28160389 1.16080615 4.81703208 2.76144029 7.1796875 5.30078125 C10.3251048 8.65627 10.3251048 8.65627 13.89453125 11.52734375 C14.46300781 11.98882812 15.03148437 12.4503125 15.6171875 12.92578125 C15.6171875 13.91578125 15.6171875 14.90578125 15.6171875 15.92578125 C11.57043134 15.40154238 9.84068694 13.40298527 7.1171875 10.48828125 C4.43259554 7.62441004 2.26579933 5.44327208 -1.3828125 3.92578125 C-1.9396875 4.49425781 -2.4965625 5.06273437 -3.0703125 5.6484375 C-6.83988896 9.46258666 -10.61412805 13.19409282 -14.6953125 16.67578125 C-17.636035 19.19388494 -20.09480078 21.77976513 -22.3828125 24.92578125 C-21.898125 24.42949219 -21.4134375 23.93320312 -20.9140625 23.421875 C-16.79765466 19.25005398 -12.59511379 15.2725847 -8.1328125 11.47265625 C-6.22321883 9.84387306 -6.22321883 9.84387306 -4.1328125 7.42578125 C-3.5553125 6.93078125 -2.9778125 6.43578125 -2.3828125 5.92578125 C1.02475359 6.31623153 2.86948109 7.72279961 5.3671875 9.98828125 C6.058125 10.6121875 6.7490625 11.23609375 7.4609375 11.87890625 C10.30935337 14.58283725 13.05165234 17.38062133 15.7578125 20.2265625 C17.62027014 21.92859837 19.31529132 22.92252119 21.6171875 23.92578125 C20.9571875 23.32765625 20.2971875 22.72953125 19.6171875 22.11328125 C17.6171875 19.92578125 17.6171875 19.92578125 17.6171875 16.92578125 C20.9892924 18.37096906 23.31599113 20.04928578 25.6171875 22.92578125 C25.9296875 25.61328125 25.9296875 25.61328125 25.6171875 27.92578125 C24.6171875 28.92578125 24.6171875 28.92578125 22.1171875 29.05078125 C19.6171875 28.92578125 19.6171875 28.92578125 18.6171875 27.92578125 C18.6171875 31.88578125 18.6171875 35.84578125 18.6171875 39.92578125 C19.4834375 39.26578125 20.3496875 38.60578125 21.2421875 37.92578125 C24.83691561 35.795572 26.5337167 35.45095906 30.6171875 35.92578125 C31.6171875 36.92578125 31.6171875 36.92578125 32.05078125 39.6015625 C31.43677139 44.30897139 29.15790982 46.08461856 25.6796875 49.11328125 C25.08212646 49.64356934 24.48456543 50.17385742 23.86889648 50.72021484 C19.37145702 54.57066699 15.54159482 57.0107056 9.6171875 57.92578125 C7.90789063 58.22162109 7.90789063 58.22162109 6.1640625 58.5234375 C-3.10688433 59.98778161 -9.46797146 60.67958399 -18.015625 56.60546875 C-20.36474904 55.66336688 -20.36474904 55.66336688 -22.45703125 56.796875 C-23.09253906 57.16941406 -23.72804688 57.54195312 -24.3828125 57.92578125 C-28.0703125 58.11328125 -28.0703125 58.11328125 -31.3828125 57.92578125 C-32.3828125 56.92578125 -32.3828125 56.92578125 -32.4453125 53.86328125 C-32.4246875 52.89390625 -32.4040625 51.92453125 -32.3828125 50.92578125 C-31.7228125 50.92578125 -31.0628125 50.92578125 -30.3828125 50.92578125 C-30.0528125 51.91578125 -29.7228125 52.90578125 -29.3828125 53.92578125 C-28.0628125 54.25578125 -26.7428125 54.58578125 -25.3828125 54.92578125 C-25.7128125 47.33578125 -26.0428125 39.74578125 -26.3828125 31.92578125 C-27.3728125 31.92578125 -28.3628125 31.92578125 -29.3828125 31.92578125 C-29.7128125 37.20578125 -30.0428125 42.48578125 -30.3828125 47.92578125 C-31.0428125 47.92578125 -31.7028125 47.92578125 -32.3828125 47.92578125 C-32.40965237 44.94655532 -32.42957287 41.9675683 -32.4453125 38.98828125 C-32.45369141 38.13814453 -32.46207031 37.28800781 -32.47070312 36.41210938 C-32.47392578 35.60322266 -32.47714844 34.79433594 -32.48046875 33.9609375 C-32.48570557 33.21207275 -32.49094238 32.46320801 -32.49633789 31.69165039 C-32.3828125 29.92578125 -32.3828125 29.92578125 -31.3828125 28.92578125 C-29.71664135 28.88514293 -28.04893155 28.88306025 -26.3828125 28.92578125 C-26.6509375 28.20390625 -26.9190625 27.48203125 -27.1953125 26.73828125 C-27.3828125 23.92578125 -27.3828125 23.92578125 -25.1328125 21.30078125 C-23.69178018 20.05625334 -22.24524815 18.81658748 -20.75390625 17.6328125 C-18.82377297 15.22976907 -18.87432148 13.28143396 -18.6953125 10.23828125 C-18.62957031 9.24441406 -18.56382813 8.25054687 -18.49609375 7.2265625 C-18.45871094 6.46730469 -18.42132813 5.70804687 -18.3828125 4.92578125 C-17.73054688 4.98378906 -17.07828125 5.04179688 -16.40625 5.1015625 C-11.25421833 5.50966568 -11.25421833 5.50966568 -6.55859375 3.77734375 C-6.06746094 3.31070312 -5.57632812 2.8440625 -5.0703125 2.36328125 C-2.3828125 -0.07421875 -2.3828125 -0.07421875 0 0 Z M-16.3828125 7.92578125 C-16.3828125 9.57578125 -16.3828125 11.22578125 -16.3828125 12.92578125 C-14.3428406 11.56254382 -14.3428406 11.56254382 -12.3828125 9.92578125 C-12.3828125 9.26578125 -12.3828125 8.60578125 -12.3828125 7.92578125 C-13.7028125 7.92578125 -15.0228125 7.92578125 -16.3828125 7.92578125 Z M-9.5703125 16.36328125 C-10.22451172 16.95560547 -10.87871094 17.54792969 -11.55273438 18.15820312 C-15.19757433 21.70427319 -15.19757433 21.70427319 -16.80712891 26.40673828 C-16.85265205 29.16042046 -16.85265205 29.16042046 -16.3828125 32.92578125 C-11.9278125 34.90578125 -11.9278125 34.90578125 -7.3828125 36.92578125 C-7.0528125 33.29578125 -6.7228125 29.66578125 -6.3828125 25.92578125 C-0.4428125 25.43078125 -0.4428125 25.43078125 5.6171875 24.92578125 C5.6171875 29.54578125 5.6171875 34.16578125 5.6171875 38.92578125 C6.9371875 39.25578125 8.2571875 39.58578125 9.6171875 39.92578125 C9.9471875 41.57578125 10.2771875 43.22578125 10.6171875 44.92578125 C12.5971875 44.43078125 12.5971875 44.43078125 14.6171875 43.92578125 C16.39179709 31.94635144 16.39179709 31.94635144 13.29150391 20.65527344 C9.66207247 16.31004622 5.39773487 12.92544951 0.6171875 9.92578125 C-4.13311828 9.92578125 -6.29653377 13.16830963 -9.5703125 16.36328125 Z M-21.9453125 28.42578125 C-22.4196875 28.92078125 -22.8940625 29.41578125 -23.3828125 29.92578125 C-23.0528125 30.91578125 -22.7228125 31.90578125 -22.3828125 32.92578125 C-21.3928125 32.92578125 -20.4028125 32.92578125 -19.3828125 32.92578125 C-19.3828125 30.94578125 -19.3828125 28.96578125 -19.3828125 26.92578125 C-20.62357552 26.81035928 -20.62357552 26.81035928 -21.9453125 28.42578125 Z M-4.3828125 27.92578125 C-4.40970466 29.40485017 -4.42915871 30.88405608 -4.4453125 32.36328125 C-4.45691406 33.18699219 -4.46851562 34.01070312 -4.48046875 34.859375 C-4.61548598 36.91742063 -4.61548598 36.91742063 -3.3828125 37.92578125 C-1.38322886 37.96658908 0.61764004 37.96832481 2.6171875 37.92578125 C2.6171875 34.62578125 2.6171875 31.32578125 2.6171875 27.92578125 C0.3071875 27.92578125 -2.0028125 27.92578125 -4.3828125 27.92578125 Z M-22.3828125 34.92578125 C-22.3828125 40.53578125 -22.3828125 46.14578125 -22.3828125 51.92578125 C-13.17053569 56.03125244 -7.25910393 57.55231146 2.6171875 55.92578125 C4.10025391 55.85423828 4.10025391 55.85423828 5.61328125 55.78125 C14.18300033 55.1237553 18.44945079 51.25640052 24.21875 45.359375 C26.6171875 42.92578125 26.6171875 42.92578125 28.6171875 41.92578125 C28.6171875 40.93578125 28.6171875 39.94578125 28.6171875 38.92578125 C25.19324374 39.5255408 23.44545264 40.78503933 20.8046875 42.98828125 C14.47800642 47.3307323 7.99246615 46.45205742 0.6171875 45.92578125 C-0.65511719 45.84457031 -1.92742188 45.76335938 -3.23828125 45.6796875 C-6.29094171 45.46330481 -9.3361717 45.213491 -12.3828125 44.92578125 C-12.3828125 44.26578125 -12.3828125 43.60578125 -12.3828125 42.92578125 C-11.69316406 42.99796875 -11.00351562 43.07015625 -10.29296875 43.14453125 C-4.28692591 43.73772067 1.5828875 44.0247042 7.6171875 43.92578125 C5.3298626 40.77085035 2.7926924 40.35935814 -0.9309082 39.74731445 C-1.63691162 39.6412085 -2.34291504 39.53510254 -3.0703125 39.42578125 C-8.84759821 38.46516438 -13.94911318 37.16318685 -19.3828125 34.92578125 C-20.3728125 34.92578125 -21.3628125 34.92578125 -22.3828125 34.92578125 Z \" fill=\"#FFFFFF\" transform=\"translate(32.3828125,2.07421875)\"><\/path><\/svg>\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tReal Estate\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tTech and Software\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tSemi-Government Companies\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t\t\n\t\t\t\t<div aria-hidden=\"true\" class=\"deensimc-marquee-group\">\n\t\t\t\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\"><path d=\"M0 0 C0.98797577 -0.0127597 1.97595154 -0.02551941 2.99386597 -0.03866577 C4.06468414 -0.04089142 5.13550232 -0.04311707 6.23876953 -0.04541016 C7.33625519 -0.05206696 8.43374084 -0.05872375 9.56448364 -0.06558228 C11.88965169 -0.07572214 14.21484892 -0.08039889 16.54003906 -0.08007812 C20.10026007 -0.08444649 23.6592372 -0.1207404 27.21923828 -0.15869141 C29.47574445 -0.16456016 31.73225652 -0.16852916 33.98876953 -0.17041016 C35.05553925 -0.18478119 36.12230896 -0.19915222 37.22140503 -0.21395874 C44.59787522 -0.16830829 44.59787522 -0.16830829 47.92578125 2.18554688 C50.11186083 5.66953544 49.51550473 8.25668689 49.24658203 12.29052734 C46.60658203 12.29052734 43.96658203 12.29052734 41.24658203 12.29052734 C40.58658203 13.61052734 39.92658203 14.93052734 39.24658203 16.29052734 C36.37158203 16.47802734 36.37158203 16.47802734 33.24658203 16.29052734 C32.58658203 15.30052734 31.92658203 14.31052734 31.24658203 13.29052734 C28.83087073 12.78148351 28.83087073 12.78148351 26.02001953 12.77880859 C24.98876953 12.74335937 23.95751953 12.70791016 22.89501953 12.67138672 C21.81478516 12.64882813 20.73455078 12.62626953 19.62158203 12.60302734 C18.53361328 12.56886719 17.44564453 12.53470703 16.32470703 12.49951172 C13.6321014 12.416844 10.93982912 12.34775647 8.24658203 12.29052734 C7.58658203 10.97052734 6.92658203 9.65052734 6.24658203 8.29052734 C4.26658203 8.29052734 2.28658203 8.29052734 0.24658203 8.29052734 C-0.41341797 9.61052734 -1.07341797 10.93052734 -1.75341797 12.29052734 C-3.40341797 12.29052734 -5.05341797 12.29052734 -6.75341797 12.29052734 C-6.80737275 10.66588892 -6.84618992 9.04074193 -6.87841797 7.41552734 C-6.90162109 6.51060547 -6.92482422 5.60568359 -6.94873047 4.67333984 C-6.56949959 0.04672306 -3.99030774 0.03489635 0 0 Z M33.24658203 7.29052734 C33.24658203 7.62052734 33.24658203 7.95052734 33.24658203 8.29052734 C35.22658203 8.29052734 37.20658203 8.29052734 39.24658203 8.29052734 C39.24658203 7.96052734 39.24658203 7.63052734 39.24658203 7.29052734 C37.26658203 7.29052734 35.28658203 7.29052734 33.24658203 7.29052734 Z M31.24658203 9.29052734 C32.24658203 11.29052734 32.24658203 11.29052734 32.24658203 11.29052734 Z \" fill=\"#FFFFFF\" transform=\"translate(10.75341796875,43.70947265625)\"><\/path><path d=\"M0 0 C18.48 0 36.96 0 56 0 C56 1.98 56 3.96 56 6 C37.52 6 19.04 6 0 6 C0 4.02 0 2.04 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(4,4)\"><\/path><path d=\"M0 0 C1.32 0 2.64 0 4 0 C4 1.32 4 2.64 4 4 C5.2065625 4.185625 5.2065625 4.185625 6.4375 4.375 C7.7059375 4.684375 7.7059375 4.684375 9 5 C10.38550197 7.77100394 10.1877467 9.9334706 10 13 C9.01 14.485 9.01 14.485 8 16 C6.68 16 5.36 16 4 16 C4 13.69 4 11.38 4 9 C2.68 9 1.36 9 0 9 C0 11.31 0 13.62 0 16 C-2.4375 15.625 -2.4375 15.625 -5 15 C-6.38550197 12.22899606 -6.1877467 10.0665294 -6 7 C-5.34 6.01 -4.68 5.02 -4 4 C-2.68 4 -1.36 4 0 4 C0 2.68 0 1.36 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(50,26)\"><\/path><path d=\"M0 0 C2.64 0 5.28 0 8 0 C8 3.3 8 6.6 8 10 C5.36 10 2.72 10 0 10 C0 6.7 0 3.4 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(6,12)\"><\/path><path d=\"M0 0 C1.51400391 0.01740234 1.51400391 0.01740234 3.05859375 0.03515625 C4.07050781 0.04417969 5.08242188 0.05320313 6.125 0.0625 C7.29869141 0.07990234 7.29869141 0.07990234 8.49609375 0.09765625 C8.49609375 2.07765625 8.49609375 4.05765625 8.49609375 6.09765625 C3.87609375 6.09765625 -0.74390625 6.09765625 -5.50390625 6.09765625 C-3.11341497 0.12142804 -3.11341497 0.12142804 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(19.50390625,35.90234375)\"><\/path><path d=\"M0 0 C3.96 0 7.92 0 12 0 C12 1.98 12 3.96 12 6 C8.04 6 4.08 6 0 6 C0 4.02 0 2.04 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(4,24)\"><\/path><path d=\"M0 0 C3.96 0 7.92 0 12 0 C12 1.98 12 3.96 12 6 C8.04 6 4.08 6 0 6 C0 4.02 0 2.04 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(46,18)\"><\/path><path d=\"M0 0 C7.82152466 -0.92017937 7.82152466 -0.92017937 10.7109375 1.3359375 C12.0625 3 12.0625 3 14 6 C9.38 6 4.76 6 0 6 C0 4.02 0 2.04 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(30,36)\"><\/path><path d=\"M0 0 C3 0.125 3 0.125 4 1.125 C4.125 4.125 4.125 4.125 4 7.125 C3 8.125 3 8.125 0 8.25 C-3 8.125 -3 8.125 -4 7.125 C-4.125 4.125 -4.125 4.125 -4 1.125 C-3 0.125 -3 0.125 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(14,51.875)\"><\/path><path d=\"M0 0 C1.32 0 2.64 0 4 0 C4 2.64 4 5.28 4 8 C2.68 8 1.36 8 0 8 C0 5.36 0 2.72 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(8,32)\"><\/path><path d=\"M0 0 C2.64 0 5.28 0 8 0 C8 1.32 8 2.64 8 4 C5.36 4 2.72 4 0 4 C0 2.68 0 1.36 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(48,12)\"><\/path><\/svg>\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tAutomotive\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\"><path d=\"M0 0 C7.09046636 4.26619657 12.00533128 9.23677697 14.77734375 17.1328125 C16.91786934 26.22687981 15.97967358 34.77076366 11.4375 42.9375 C10.674375 43.88625 9.91125 44.835 9.125 45.8125 C7.20159051 47.74767091 7.20159051 47.74767091 7.5625 49.9375 C8.21281278 51.4239292 8.88259461 52.90187165 9.5625 54.375 C10.4375 56.9375 10.4375 56.9375 9.4375 61.9375 C-5.7425 61.9375 -20.9225 61.9375 -36.5625 61.9375 C-37.68995253 56.30023735 -37.00967364 55.72988171 -34.5625 50.9375 C-34.97472769 47.4188422 -36.70399688 44.83698935 -38.5625 41.875 C-43.31443576 34.27875654 -43.82446333 26.26719007 -42.06640625 17.44921875 C-40.46329882 12.78481014 -37.85318901 9.49500163 -34.5625 5.9375 C-33.5725 6.2675 -32.5825 6.5975 -31.5625 6.9375 C-32.2225 8.2575 -32.8825 9.5775 -33.5625 10.9375 C-32.9025 11.39125 -32.2425 11.845 -31.5625 12.3125 C-30.9025 12.84875 -30.2425 13.385 -29.5625 13.9375 C-29.5625 14.5975 -29.5625 15.2575 -29.5625 15.9375 C-28.634375 16.185 -27.70625 16.4325 -26.75 16.6875 C-23.37875958 18.00955507 -22.16607433 18.73035135 -20.5625 21.9375 C-20.875 24.1875 -20.875 24.1875 -21.5625 25.9375 C-23.8725 26.2675 -26.1825 26.5975 -28.5625 26.9375 C-29.0575 29.4125 -29.0575 29.4125 -29.5625 31.9375 C-35.1875 32.1875 -35.1875 32.1875 -38.5625 29.9375 C-37.2425 33.5675 -35.9225 37.1975 -34.5625 40.9375 C-31.54166999 41.06119162 -31.54166999 41.06119162 -28.625 40.1875 C-25.5625 39.9375 -25.5625 39.9375 -23.25 41.625 C-21.63402381 43.83948589 -20.94570557 45.25506099 -20.5625 47.9375 C-20.665625 47.050625 -20.76875 46.16375 -20.875 45.25 C-20.5625 41.9375 -20.5625 41.9375 -18.4375 39 C-15.5625 36.9375 -15.5625 36.9375 -12.4375 36.875 C-9.0998595 38.10847584 -8.0810918 38.73158397 -6.5625 41.9375 C-6.375 45.6875 -6.375 45.6875 -6.5625 48.9375 C-6.294375 47.82375 -6.02625 46.71 -5.75 45.5625 C-4.5625 41.9375 -4.5625 41.9375 -1.5625 39.9375 C1.4375 40.3125 1.4375 40.3125 4.4375 40.9375 C5.4275 40.9375 6.4175 40.9375 7.4375 40.9375 C9.0875 36.6475 10.7375 32.3575 12.4375 27.9375 C9.4675 28.4325 9.4675 28.4325 6.4375 28.9375 C4.0625 27.5 4.0625 27.5 2.4375 25.9375 C2.045625 26.453125 1.65375 26.96875 1.25 27.5 C-0.5625 28.9375 -0.5625 28.9375 -3.125 28.9375 C-5.5625 27.9375 -5.5625 27.9375 -6.5625 25.5625 C-7.0575 24.263125 -7.0575 24.263125 -7.5625 22.9375 C-10.43852678 20.81832237 -13.05297825 19.58741143 -16.5625 18.9375 C-17.49673645 15.92718256 -17.60699911 15.07099732 -16.5625 11.9375 C-14.5 11.25 -14.5 11.25 -12.5625 10.9375 C-12.5625 9.9475 -12.5625 8.9575 -12.5625 7.9375 C-13.8825 7.6075 -15.2025 7.2775 -16.5625 6.9375 C-16.8925 5.2875 -17.2225 3.6375 -17.5625 1.9375 C-22.0175 2.4325 -22.0175 2.4325 -26.5625 2.9375 C-26.5625 1.9475 -26.5625 0.9575 -26.5625 -0.0625 C-18.84018593 -3.78175765 -7.76587467 -3.63203985 0 0 Z M-13.5625 0.9375 C-13.29573796 2.92241642 -13.29573796 2.92241642 -12.5625 4.9375 C-11.5725 5.2675 -10.5825 5.5975 -9.5625 5.9375 C-9.5625 8.5775 -9.5625 11.2175 -9.5625 13.9375 C-10.5525 14.2675 -11.5425 14.5975 -12.5625 14.9375 C-10.17676621 16.82963369 -8.49074652 17.96141783 -5.5625 18.9375 C-3.875 22 -3.875 22 -2.5625 24.9375 C-1.9025 23.6175 -1.2425 22.2975 -0.5625 20.9375 C5.1875 22.6875 5.1875 22.6875 7.4375 24.9375 C9.54570797 24.6189823 9.54570797 24.6189823 11.4375 23.9375 C11.00492927 17.01636824 8.66118732 11.94229497 3.5390625 7.16796875 C-1.77031513 2.98759671 -6.65364434 0.53109673 -13.5625 0.9375 Z M-36.5625 14.9375 C-37.09440541 16.37094 -37.61265258 17.80945367 -38.125 19.25 C-38.41503906 20.05050781 -38.70507812 20.85101563 -39.00390625 21.67578125 C-39.81165625 24.0808174 -39.81165625 24.0808174 -38.5625 26.9375 C-36.9125 26.9375 -35.2625 26.9375 -33.5625 26.9375 C-33.2325 25.2875 -32.9025 23.6375 -32.5625 21.9375 C-30.9125 21.6075 -29.2625 21.2775 -27.5625 20.9375 C-31.39331939 16.75572976 -31.39331939 16.75572976 -36.5625 14.9375 Z M-27.5625 20.9375 C-27.2325 21.5975 -26.9025 22.2575 -26.5625 22.9375 C-25.9025 22.6075 -25.2425 22.2775 -24.5625 21.9375 C-25.5525 21.6075 -26.5425 21.2775 -27.5625 20.9375 Z M-15.5625 40.9375 C-16.91868499 42.06284105 -16.91868499 42.06284105 -16.625 45 C-16.604375 45.969375 -16.58375 46.93875 -16.5625 47.9375 C-14.90635343 48.31968767 -13.23792976 48.65145102 -11.5625 48.9375 C-10.20631501 47.81215895 -10.20631501 47.81215895 -10.5 44.875 C-10.520625 43.905625 -10.54125 42.93625 -10.5625 41.9375 C-12.21864657 41.55531233 -13.88707024 41.22354898 -15.5625 40.9375 Z M-29.5625 43.9375 C-29.8925 45.5875 -30.2225 47.2375 -30.5625 48.9375 C-28.5825 49.9275 -28.5825 49.9275 -26.5625 50.9375 C-25.26616379 49.87104885 -25.26616379 49.87104885 -25.5 47.375 C-25.520625 46.570625 -25.54125 45.76625 -25.5625 44.9375 C-26.8825 44.6075 -28.2025 44.2775 -29.5625 43.9375 Z M-0.5625 43.9375 C-1.85883621 45.00395115 -1.85883621 45.00395115 -1.625 47.5 C-1.604375 48.304375 -1.58375 49.10875 -1.5625 49.9375 C-0.2425 49.9375 1.0775 49.9375 2.4375 49.9375 C2.7675 48.2875 3.0975 46.6375 3.4375 44.9375 C1.49146726 44.34679986 1.49146726 44.34679986 -0.5625 43.9375 Z M-18.5625 51.9375 C-20.93230013 54.89127498 -20.93230013 54.89127498 -20.5625 58.9375 C-15.9425 58.9375 -11.3225 58.9375 -6.5625 58.9375 C-7.25552969 54.33217611 -7.25552969 54.33217611 -8.5625 51.9375 C-10.18668745 51.85659029 -11.81201745 51.79835005 -13.4375 51.75 C-14.34242187 51.71519531 -15.24734375 51.68039063 -16.1796875 51.64453125 C-16.96601563 51.74121094 -17.75234375 51.83789062 -18.5625 51.9375 Z M-32.5625 53.9375 C-32.8925 55.5875 -33.2225 57.2375 -33.5625 58.9375 C-30.2625 58.9375 -26.9625 58.9375 -23.5625 58.9375 C-23.5625 57.2875 -23.5625 55.6375 -23.5625 53.9375 C-26.5325 53.9375 -29.5025 53.9375 -32.5625 53.9375 Z M-3.5625 53.9375 C-3.5625 55.5875 -3.5625 57.2375 -3.5625 58.9375 C-0.2625 58.9375 3.0375 58.9375 6.4375 58.9375 C6.1075 57.2875 5.7775 55.6375 5.4375 53.9375 C2.4675 53.9375 -0.5025 53.9375 -3.5625 53.9375 Z \" fill=\"#FFFFFF\" transform=\"translate(45.5625,2.0625)\"><\/path><path d=\"M0 0 C1.32 0 2.64 0 4 0 C4 0.99 4 1.98 4 3 C2.68 2.67 1.36 2.34 0 2 C0 1.34 0 0.68 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(14,5)\"><\/path><\/svg>\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tCulture\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\"><path d=\"M0 0 C1.14339844 0.38285156 2.28679688 0.76570312 3.46484375 1.16015625 C4.54894531 1.54558594 5.63304687 1.93101563 6.75 2.328125 C7.73484375 2.67262695 8.7196875 3.01712891 9.734375 3.37207031 C12 4.75 12 4.75 12.828125 7.40136719 C12.88484375 8.17641602 12.9415625 8.95146484 13 9.75 C8.86327942 11.35539152 4.71916779 12.93940294 0.56713867 14.50463867 C-0.8422698 15.03928646 -2.24955231 15.57957565 -3.65454102 16.12573242 C-5.682241 16.91280491 -7.71688782 17.67882803 -9.75390625 18.44140625 C-10.97408447 18.90748291 -12.1942627 19.37355957 -13.45141602 19.85375977 C-19.68944622 21.42925401 -24.71485988 19.68553143 -30.58984375 17.46484375 C-32.38325195 16.79291992 -32.38325195 16.79291992 -34.21289062 16.10742188 C-35.44201172 15.63884766 -36.67113281 15.17027344 -37.9375 14.6875 C-39.20613503 14.20963505 -40.4750134 13.73241559 -41.74414062 13.25585938 C-44.83187615 12.09355589 -47.91698986 10.92476771 -51 9.75 C-50.86914062 7.41943359 -50.86914062 7.41943359 -50 4.75 C-47.45898438 3.24853516 -47.45898438 3.24853516 -44.09375 2.0390625 C-42.87429687 1.59949219 -41.65484375 1.15992188 -40.3984375 0.70703125 C-39.75745117 0.48869629 -39.11646484 0.27036133 -38.45605469 0.04541016 C-36.52415101 -0.61672258 -34.61062986 -1.3188642 -32.6953125 -2.02734375 C-19.90756781 -6.51779917 -12.51481915 -4.48097233 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(51,10.25)\"><\/path><path d=\"M0 0 C1.17175781 0.46792969 2.34351563 0.93585937 3.55078125 1.41796875 C12.94327645 4.98181269 19.42052408 7.27821255 29 3 C30.72453889 2.42346794 32.45354591 1.86006445 34.1875 1.3125 C35.445625 0.879375 36.70375 0.44625 38 0 C38 3.96 38 7.92 38 12 C31.40819368 15.44571694 26.5613888 16.20221315 19.25 16.25 C18.4765625 16.270625 17.703125 16.29125 16.90625 16.3125 C10.51428525 16.35539909 5.74048451 14.87024225 0 12 C0 8.04 0 4.08 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(13,27)\"><\/path><path d=\"M0 0 C0.06058594 1.16917969 0.12117188 2.33835937 0.18359375 3.54296875 C0.26804034 5.09115614 0.35268625 6.63933268 0.4375 8.1875 C0.47681641 8.95642578 0.51613281 9.72535156 0.55664062 10.51757812 C0.73590188 13.73049144 0.95241858 16.76706874 1.59765625 19.92578125 C2 22 2 22 1 24 C0.77377919 25.70363822 0.59111527 27.41328701 0.4375 29.125 C0.31181641 30.49011719 0.31181641 30.49011719 0.18359375 31.8828125 C0.12300781 32.58148438 0.06242187 33.28015625 0 34 C-1.9375 34.5625 -1.9375 34.5625 -4 35 C-5.70089219 33.29910781 -5.32747264 31.01353847 -5.5 28.6875 C-5.79652708 24.68701855 -5.79652708 24.68701855 -6.59375 20.76953125 C-7 19 -7 19 -6 17 C-5.80199313 13.8025557 -5.65410911 10.61238393 -5.5703125 7.41015625 C-5.4765625 5.40625 -5.4765625 5.40625 -5 2 C-2 0 -2 0 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(60,24)\"><\/path><\/svg>\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tEducation\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\"><path d=\"M0 0 C3.63 0 7.26 0 11 0 C11.02699468 3.08339204 11.0468366 6.16654719 11.0625 9.25 C11.07087891 10.12269531 11.07925781 10.99539063 11.08789062 11.89453125 C11.09272461 13.16103516 11.09272461 13.16103516 11.09765625 14.453125 C11.10551147 15.61569824 11.10551147 15.61569824 11.11352539 16.80175781 C11.00036998 18.99283598 10.60552448 20.89637861 10 23 C12.37305578 23.41780879 12.37305578 23.41780879 15 23 C15.433125 22.21625 15.86625 21.4325 16.3125 20.625 C18.2572023 17.59990754 18.84072324 17.49190073 22.1875 16.6875 C23.445625 16.460625 24.70375 16.23375 26 16 C26.144375 15.38125 26.28875 14.7625 26.4375 14.125 C27 12 27 12 28 10 C26.35 10 24.7 10 23 10 C23.33 8.02 23.66 6.04 24 4 C25.65 4 27.3 4 29 4 C29.33 2.68 29.66 1.36 30 0 C32.97 0 35.94 0 39 0 C39.495 1.485 39.495 1.485 40 3 C40.825 3.28875 41.65 3.5775 42.5 3.875 C43.325 4.24625 44.15 4.6175 45 5 C45.8125 7.625 45.8125 7.625 46 10 C44.35 10 42.7 10 41 10 C41.66 11.98 42.32 13.96 43 16 C42.34 16 41.68 16 41 16 C41.34224609 16.85271484 41.34224609 16.85271484 41.69140625 17.72265625 C43.66411246 23.02153974 44.29178872 26.4805391 43 32 C43.66 32 44.32 32 45 32 C44.98839844 32.61488281 44.97679687 33.22976562 44.96484375 33.86328125 C44.95582031 34.67152344 44.94679687 35.47976562 44.9375 36.3125 C44.92589844 37.11300781 44.91429687 37.91351563 44.90234375 38.73828125 C44.90342145 41.16861334 44.90342145 41.16861334 46 44 C46.495 48.95 46.495 48.95 47 54 C25.88 54 4.76 54 -17 54 C-16.67 52.35 -16.34 50.7 -16 49 C-15.01 49 -14.02 49 -13 49 C-13 49.66 -13 50.32 -13 51 C-12.01 51 -11.02 51 -10 51 C-10 47.37 -10 43.74 -10 40 C-10.99 40 -11.98 40 -13 40 C-13 42.31 -13 44.62 -13 47 C-13.99 47 -14.98 47 -16 47 C-16 43.7 -16 40.4 -16 37 C-14.02 37 -12.04 37 -10 37 C-10.01160156 36.07316406 -10.02320313 35.14632812 -10.03515625 34.19140625 C-10.04417969 32.99386719 -10.05320312 31.79632813 -10.0625 30.5625 C-10.07410156 29.36753906 -10.08570313 28.17257813 -10.09765625 26.94140625 C-10 24 -10 24 -9 23 C-7.33382885 22.95936168 -5.66611905 22.957279 -4 23 C-4 23.99 -4 24.98 -4 26 C-4.99 26 -5.98 26 -7 26 C-7 34.25 -7 42.5 -7 51 C-6.01 51 -5.02 51 -4 51 C-4.061875 49.88625 -4.12375 48.7725 -4.1875 47.625 C-4.125625 46.42875 -4.06375 45.2325 -4 44 C-0.18977687 41.45985125 2.53470816 41.41393045 7 42 C9 43.125 9 43.125 10 45 C10.1875 48.1875 10.1875 48.1875 10 51 C10.99 51 11.98 51 13 51 C13 42.75 13 34.5 13 26 C7.72 26 2.44 26 -3 26 C-3 25.01 -3 24.02 -3 23 C-1.68 23 -0.36 23 1 23 C0.7525 21.205625 0.7525 21.205625 0.5 19.375 C-0.23219971 12.92958003 -0.08292095 6.47704735 0 0 Z M4 3 C4 3.99 4 4.98 4 6 C4.99 6 5.98 6 7 6 C7 5.01 7 4.02 7 3 C6.01 3 5.02 3 4 3 Z M32 3 C32 3.33 32 3.66 32 4 C33.65 4 35.3 4 37 4 C37 3.67 37 3.34 37 3 C35.35 3 33.7 3 32 3 Z M40 7 C40.33 7.99 40.66 8.98 41 10 C41.33 9.01 41.66 8.02 42 7 C41.34 7 40.68 7 40 7 Z M4 9 C4 9.66 4 10.32 4 11 C4.99 11 5.98 11 7 11 C7 10.34 7 9.68 7 9 C6.01 9 5.02 9 4 9 Z M33 11 C32.34 12.32 31.68 13.64 31 15 C32.98 15.99 32.98 15.99 35 17 C35.99 16.34 36.98 15.68 38 15 C38 14.34 38 13.68 38 13 C35.525 12.01 35.525 12.01 33 11 Z M4 14 C4 14.99 4 15.98 4 17 C4.99 17 5.98 17 7 17 C7 16.01 7 15.02 7 14 C6.01 14 5.02 14 4 14 Z M38 18 C39 20 39 20 39 20 Z M4 19 C4 20.32 4 21.64 4 23 C4.99 23 5.98 23 7 23 C7 21.68 7 20.36 7 19 C6.01 19 5.02 19 4 19 Z M19 22 C18.75787127 23.98128508 18.75787127 23.98128508 18.875 26.125 C18.936875 28.043125 18.936875 28.043125 19 30 C19.99 30 20.98 30 22 30 C22 32.31 22 34.62 22 37 C21.01 37 20.02 37 19 37 C19 35.35 19 33.7 19 32 C18.01 32 17.02 32 16 32 C16 38.27 16 44.54 16 51 C16.99 51 17.98 51 19 51 C19 46.71 19 42.42 19 38 C19.99 38 20.98 38 22 38 C22 42.29 22 46.58 22 51 C22.33 51 22.66 51 23 51 C23.59055954 46.32712595 24.17436068 41.65349747 24.75195312 36.97900391 C24.95699946 35.34307321 25.17243677 33.70844858 25.390625 32.07421875 C25.85828638 28.41292243 26.04103798 25.53796366 25 22 C25.66 22 26.32 22 27 22 C27 21.34 27 20.68 27 20 C22.50695418 19.57496554 22.50695418 19.57496554 19 22 Z M30 23 C30 23.66 30 24.32 30 25 C32.475 25.99 32.475 25.99 35 27 C36.32 25.68 37.64 24.36 39 23 C34.98990901 20.32660601 34.01009099 20.32660601 30 23 Z M38 28 C38.66 28.66 39.32 29.32 40 30 C40 29.34 40 28.68 40 28 C39.34 28 38.68 28 38 28 Z M34 30 C31.12608179 31.17274994 31.12608179 31.17274994 29 33 C30.69495956 34.66846734 30.69495956 34.66846734 33 36 C36.37036311 35.75925978 37.58798021 35.41201979 40 33 C37.30128645 31.1915405 37.30128645 31.1915405 34 30 Z M28 37 C27.67 37.66 27.34 38.32 27 39 C27.99 38.67 28.98 38.34 30 38 C29.34 37.67 28.68 37.34 28 37 Z M39 37 C39 37.66 39 38.32 39 39 C39.66 39 40.32 39 41 39 C41 38.34 41 37.68 41 37 C40.34 37 39.68 37 39 37 Z M29.625 41.4375 C29.08875 41.953125 28.5525 42.46875 28 43 C31.38943198 44.8386571 31.38943198 44.8386571 35 46 C38.4030585 44.84237864 38.4030585 44.84237864 41 43 C37.12472171 40.41648114 33.84837727 38.88124534 29.625 41.4375 Z M-1 46 C-1.04063832 47.66617115 -1.042721 49.33388095 -1 51 C1.64 51 4.28 51 7 51 C7.042721 49.33388095 7.04063832 47.66617115 7 46 C5.88163776 44.65595225 5.88163776 44.65595225 3 44.875 C0.11836224 44.65595225 0.11836224 44.65595225 -1 46 Z M26 46 C26.33 47.32 26.66 48.64 27 50 C28.32 49.01 29.64 48.02 31 47 C29.35 46.67 27.7 46.34 26 46 Z M40 46 C39.34 46.66 38.68 47.32 38 48 C40.475 48.99 40.475 48.99 43 50 C42.67 48.68 42.34 47.36 42 46 C41.34 46 40.68 46 40 46 Z M34 49 C33.34 49.66 32.68 50.32 32 51 C33.65 51 35.3 51 37 51 C36.01 50.34 35.02 49.68 34 49 Z \" fill=\"#FFFFFF\" transform=\"translate(17,5)\"><\/path><path d=\"M0 0 C-0.75 6.75 -0.75 6.75 -3 9 C-3.99 9 -4.98 9 -6 9 C-6.36521739 3.52173913 -6.36521739 3.52173913 -4.6875 1.125 C-3 0 -3 0 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(23,32)\"><\/path><\/svg>\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tElectrical and Energy\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\"><path d=\"M0 0 C4.86281844 4.21444265 8.69457052 8.29478995 9.23828125 14.890625 C9.39316641 21.90121651 9.42601512 26.4391092 5 32 C-0.22669182 37.21481297 -3.78403188 39.14579975 -11.3125 39.25 C-18.03516645 39.18284795 -21.61858506 38.10450622 -26.6875 33.625 C-30.86994998 28.87735408 -32.69098257 25.09017434 -33.3125 18.875 C-32.81213304 12.67044967 -31.00470839 6.36252316 -26.25 2.0625 C-17.65591306 -3.39143979 -9.30694725 -4.93758044 0 0 Z M-13 6 C-13.28875 6.78375 -13.5775 7.5675 -13.875 8.375 C-15 11 -15 11 -17 13 C-17.14768913 15.51749828 -17.14768913 15.51749828 -16 18 C-13.03292954 19.85916824 -13.03292954 19.85916824 -10 21 C-10 21.66 -10 22.32 -10 23 C-11.98 23 -13.96 23 -16 23 C-15.5359375 23.86625 -15.5359375 23.86625 -15.0625 24.75 C-14.07416636 26.84294184 -13.4831387 28.74535275 -13 31 C-12.01 31 -11.02 31 -10 31 C-9.690625 30.195625 -9.38125 29.39125 -9.0625 28.5625 C-8 26 -8 26 -7 25 C-6.95919217 23.00041636 -6.95745644 20.99954746 -7 19 C-8.98 18.01 -10.96 17.02 -13 16 C-13 15.01 -13 14.02 -13 13 C-10.03 13.495 -10.03 13.495 -7 14 C-7.309375 13.4225 -7.61875 12.845 -7.9375 12.25 C-8.92583364 10.15705816 -9.5168613 8.25464725 -10 6 C-10.99 6 -11.98 6 -13 6 Z \" fill=\"#FFFFFF\" transform=\"translate(55,25)\"><\/path><path d=\"M0 0 C1.13985352 -0.0299707 1.13985352 -0.0299707 2.30273438 -0.06054688 C9.2585454 -0.05460681 14.46393562 2.09245409 19.625 6.75 C21.0625 9.4375 21.0625 9.4375 21.1875 12.9375 C19.84061721 17.12780203 17.88709009 19.40330567 14.0625 21.4375 C4.16514058 24.82375142 -6.33746543 24.83751482 -15.984375 20.703125 C-18.2893228 19.20951883 -19.50979655 17.77734733 -20.9375 15.4375 C-21.4375 12 -21.4375 12 -20.9375 8.4375 C-15.53614197 1.23568929 -8.44581843 -0.0784 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(20.9375,-0.4375)\"><\/path><path d=\"M0 0 C0.52464844 0.33773438 1.04929688 0.67546875 1.58984375 1.0234375 C9.71382914 5.70047401 17.83891313 6.28794336 27 7 C25.7038361 10.05621803 24.32165269 12.60547032 22 15 C16.0019965 16.79731115 10.35839947 14.74871554 4.91015625 12.16796875 C2.88494164 10.92964734 1.45570972 9.88066846 0 8 C-0.39078556 5.27492202 -0.13616953 2.76878044 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(0,19)\"><\/path><path d=\"M0 0 C0.7734375 0.34933594 1.546875 0.69867188 2.34375 1.05859375 C8.32178877 3.67028643 13.47271928 5.62342611 20 6 C20.99 8.97 21.98 11.94 23 15 C15.21569061 15.43246163 8.31307515 14.38541411 1.875 9.75 C-0.48366457 6.2906253 -0.40222929 4.10273875 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(0,42)\"><\/path><path d=\"M0 0 C0.99 0.4021875 0.99 0.4021875 2 0.8125 C2.99 1.204375 3.98 1.59625 5 2 C5.92425781 2.37898438 5.92425781 2.37898438 6.8671875 2.765625 C11.27712589 4.51587292 15.27918074 5.50824799 20 6 C20 8.97 20 11.94 20 15 C11.66691456 13.97521927 6.04065086 13.04065086 0 7 C-0.125 3.375 -0.125 3.375 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(0,31)\"><\/path><\/svg>\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tFinance\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\"><path d=\"M0 0 C1.66227542 0.60390026 3.32636057 1.20284157 4.9921875 1.796875 C6.62193732 2.44252669 8.24956051 3.09357251 9.875 3.75 C10.70257813 4.059375 11.53015625 4.36875 12.3828125 4.6875 C16.47086321 6.34909481 19.24243735 7.69073291 21.5546875 11.55078125 C23.01507026 15.03596497 23.36393014 17.26971604 23 21 C22.34 21 21.68 21 21 21 C21.11795925 25.68157901 21.24218549 30.36293288 21.37231445 35.04418945 C21.41572146 36.637893 21.45739219 38.2316448 21.49731445 39.82543945 C21.55487807 42.11163908 21.61861149 44.39759449 21.68359375 46.68359375 C21.70030624 47.40026718 21.71701874 48.11694061 21.73423767 48.85533142 C21.55018654 52.21527382 21.55018654 52.21527382 23 55 C23.125 57.5 23.125 57.5 23 60 C21.22083533 61.77916467 18.61686701 61.12764835 16.2109375 61.12939453 C14.9729541 61.13254669 13.7349707 61.13569885 12.45947266 61.13894653 C11.09798141 61.13715675 9.73649049 61.1351058 8.375 61.1328125 C6.98876936 61.13348559 5.60253883 61.13445566 4.21630859 61.13571167 C1.30760578 61.1371884 -1.60106637 61.1350349 -4.50976562 61.13037109 C-8.24596598 61.12467381 -11.98209452 61.12795294 -15.71829224 61.13394356 C-18.58179266 61.13754985 -21.44527593 61.13641027 -24.30877686 61.13381577 C-25.68674732 61.13314668 -27.06471932 61.13397426 -28.44268799 61.13629532 C-30.36543754 61.13882292 -32.28819252 61.13429024 -34.2109375 61.12939453 C-35.85521729 61.12820114 -35.85521729 61.12820114 -37.53271484 61.12698364 C-40 61 -40 61 -41 60 C-41.125 57.5 -41.125 57.5 -41 55 C-40.505 54.505 -40.505 54.505 -40 54 C-39.84213692 52.14825294 -39.74892644 50.2909089 -39.68359375 48.43359375 C-39.62075195 46.7465332 -39.62075195 46.7465332 -39.55664062 45.02539062 C-39.51732422 43.84138672 -39.47800781 42.65738281 -39.4375 41.4375 C-39.39431641 40.24962891 -39.35113281 39.06175781 -39.30664062 37.83789062 C-39.20016454 34.89205216 -39.09815159 31.9461257 -39 29 C-38.01 28.67 -37.02 28.34 -36 28 C-36 35.59 -36 43.18 -36 51 C-35.01 51 -34.02 51 -33 51 C-33 42.75 -33 34.5 -33 26 C-34.65 26 -36.3 26 -38 26 C-38.33 24.35 -38.66 22.7 -39 21 C-39.66 21 -40.32 21 -41 21 C-41.41467461 16.74958524 -40.91743716 13.52263343 -38.69921875 9.82543945 C-34.80850346 5.64571557 -29.07587047 3.93760535 -23.875 1.875 C-22.6890625 1.35679687 -21.503125 0.83859375 -20.28125 0.3046875 C-12.35699427 -2.91399474 -7.77468181 -3.53248325 0 0 Z M-22 4.75 C-23.67835937 5.41515625 -23.67835937 5.41515625 -25.390625 6.09375 C-26.45796875 6.53203125 -27.5253125 6.9703125 -28.625 7.421875 C-29.60726563 7.81987305 -30.58953125 8.21787109 -31.6015625 8.62792969 C-34.25590361 10.14639437 -34.97710639 11.16748727 -36 14 C-33.69 14 -31.38 14 -29 14 C-28.67 13.01 -28.34 12.02 -28 11 C-19.42 10.67 -10.84 10.34 -2 10 C-2 10.99 -2 11.98 -2 13 C-9.92 13 -17.84 13 -26 13 C-26 17.62 -26 22.24 -26 27 C-14.78 27 -3.56 27 8 27 C8 22.38 8 17.76 8 13 C5.36 13 2.72 13 0 13 C0 12.01 0 11.02 0 10 C3.3 10.33 6.6 10.66 10 11 C10.495 12.485 10.495 12.485 11 14 C13.31 14 15.62 14 18 14 C16.97710639 11.16748727 16.25590361 10.14639437 13.6015625 8.62792969 C12.61929688 8.22993164 11.63703125 7.83193359 10.625 7.421875 C9.02398437 6.76445312 9.02398437 6.76445312 7.390625 6.09375 C6.27171875 5.6503125 5.1528125 5.206875 4 4.75 C2.88109375 4.29109375 1.7621875 3.8321875 0.609375 3.359375 C-9.13259468 -0.59388806 -12.32519599 0.78199282 -22 4.75 Z M-39 17 C-39 17.66 -39 18.32 -39 19 C-35.7 19 -32.4 19 -29 19 C-29 18.34 -29 17.68 -29 17 C-32.3 17 -35.6 17 -39 17 Z M11 17 C11 17.66 11 18.32 11 19 C14.3 19 17.6 19 21 19 C21 18.34 21 17.68 21 17 C17.7 17 14.4 17 11 17 Z M-36 21 C-36 21.66 -36 22.32 -36 23 C-33.69 23 -31.38 23 -29 23 C-29 22.34 -29 21.68 -29 21 C-31.31 21 -33.62 21 -36 21 Z M11 21 C11 21.66 11 22.32 11 23 C13.31 23 15.62 23 18 23 C18 22.34 18 21.68 18 21 C15.69 21 13.38 21 11 21 Z M-30 26 C-30 34.25 -30 42.5 -30 51 C-27.36 51 -24.72 51 -22 51 C-22 44.07 -22 37.14 -22 30 C-24.97 29.505 -24.97 29.505 -28 29 C-28.66 28.01 -29.32 27.02 -30 26 Z M15 26 C15 34.25 15 42.5 15 51 C15.99 51 16.98 51 18 51 C18 42.75 18 34.5 18 26 C17.01 26 16.02 26 15 26 Z M-19 30 C-19 36.93 -19 43.86 -19 51 C-18.01 51 -17.02 51 -16 51 C-16 44.07 -16 37.14 -16 30 C-16.99 30 -17.98 30 -19 30 Z M-13 30 C-13 31.98 -13 33.96 -13 36 C-12.05125 35.814375 -11.1025 35.62875 -10.125 35.4375 C-7 35 -7 35 -5 36 C-5 34.02 -5 32.04 -5 30 C-7.64 30 -10.28 30 -13 30 Z M-2 30 C-2 36.93 -2 43.86 -2 51 C-1.01 51 -0.02 51 1 51 C1 44.07 1 37.14 1 30 C0.01 30 -0.98 30 -2 30 Z M11 26 C10.67 26.99 10.34 27.98 10 29 C8.02 29.33 6.04 29.66 4 30 C4 36.93 4 43.86 4 51 C6.64 51 9.28 51 12 51 C12 42.75 12 34.5 12 26 C11.67 26 11.34 26 11 26 Z M-11.61328125 38.14453125 C-13.53906265 40.721281 -13.29961289 42.51096821 -13.1875 45.6875 C-13.16042969 46.68136719 -13.13335938 47.67523438 -13.10546875 48.69921875 C-13.07066406 49.45847656 -13.03585938 50.21773437 -13 51 C-12.01 51 -11.02 51 -10 51 C-10 47.37 -10 43.74 -10 40 C-9.34 40 -8.68 40 -8 40 C-8 43.63 -8 47.26 -8 51 C-7.01 51 -6.02 51 -5 51 C-4.91885894 49.22992286 -4.86074495 47.45877902 -4.8125 45.6875 C-4.77769531 44.70136719 -4.74289063 43.71523438 -4.70703125 42.69921875 C-4.77076227 39.97865275 -4.77076227 39.97865275 -6.38671875 38.14453125 C-8.58593773 36.58431052 -9.41406227 36.58431052 -11.61328125 38.14453125 Z M-36 53 C-36 53.33 -36 53.66 -36 54 C-21.81 54 -7.62 54 7 54 C7 54.99 7 55.98 7 57 C-8.18 57 -23.36 57 -39 57 C-39 57.33 -39 57.66 -39 58 C-19.2 58 0.6 58 21 58 C21 57.67 21 57.34 21 57 C17.04 57 13.08 57 9 57 C9 56.01 9 55.02 9 54 C11.97 54 14.94 54 18 54 C18 53.67 18 53.34 18 53 C0.18 53 -17.64 53 -36 53 Z \" fill=\"#FFFFFF\" transform=\"translate(41,3)\"><\/path><path d=\"M0 0 C0.33 0.33 0.66 0.66 1 1 C1.33 0.34 1.66 -0.32 2 -1 C2.99 -0.67 3.98 -0.34 5 0 C5.33 0.99 5.66 1.98 6 3 C6.66 1.68 7.32 0.36 8 -1 C8.99 -0.67 9.98 -0.34 11 0 C10.01 3.3 9.02 6.6 8 10 C6.68 10 5.36 10 4 10 C3.67 9.01 3.34 8.02 3 7 C2.278125 7.680625 1.55625 8.36125 0.8125 9.0625 C-2 11 -2 11 -4.6875 10.875 C-7 10 -7 10 -9 8 C-9.375 5.0625 -9.375 5.0625 -9 2 C-6.11353359 -1.31409106 -4.06037509 -1.31687841 0 0 Z M-5 2 C-5.33 3.65 -5.66 5.3 -6 7 C-4.68 7 -3.36 7 -2 7 C-2 5.68 -2 4.36 -2 3 C-2.99 2.67 -3.98 2.34 -5 2 Z \" fill=\"#FFFFFF\" transform=\"translate(37,18)\"><\/path><path d=\"M0 0 C0 0.99 0 1.98 0 3 C-1.65 3 -3.3 3 -5 3 C-5 4.32 -5 5.64 -5 7 C-4.67 6.67 -4.34 6.34 -4 6 C-4 5.34 -4 4.68 -4 4 C-2.35 4 -0.7 4 1 4 C0.67 5.98 0.34 7.96 0 10 C-2.8125 10.625 -2.8125 10.625 -6 11 C-9 9 -9 9 -9.8125 6.625 C-10.02443247 3.65794547 -9.71818252 2.40545553 -8 0 C-4.71023192 -1.09658936 -3.28696233 -0.79953138 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(26,18)\"><\/path><path d=\"M0 0 C0.99 0 1.98 0 3 0 C2.42655063 2.86724686 2.1385485 3.8614515 0 6 C-0.99 6 -1.98 6 -3 6 C-2.42655063 3.13275314 -2.1385485 2.1385485 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(32,6)\"><\/path><path d=\"M0 0 C0.99 0 1.98 0 3 0 C3 1.65 3 3.3 3 5 C2.01 5 1.02 5 0 5 C0 3.35 0 1.7 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(14,34)\"><\/path><path d=\"M0 0 C0.99 0 1.98 0 3 0 C3 1.65 3 3.3 3 5 C2.01 4.67 1.02 4.34 0 4 C0 2.68 0 1.36 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(47,47)\"><\/path><path d=\"M0 0 C0.99 0 1.98 0 3 0 C2.67 1.65 2.34 3.3 2 5 C1.34 5 0.68 5 0 5 C0 3.35 0 1.7 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(14,47)\"><\/path><path d=\"M0 0 C0.66 0 1.32 0 2 0 C2 1.65 2 3.3 2 5 C1.01 5 0.02 5 -1 5 C-0.67 3.35 -0.34 1.7 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(48,40)\"><\/path><path d=\"M0 0 C0.99 0.33 1.98 0.66 3 1 C3 2.32 3 3.64 3 5 C2.01 5 1.02 5 0 5 C0 3.35 0 1.7 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(14,40)\"><\/path><path d=\"M0 0 C0.66 0 1.32 0 2 0 C2 1.65 2 3.3 2 5 C1.01 4.67 0.02 4.34 -1 4 C-0.67 2.68 -0.34 1.36 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(48,34)\"><\/path><\/svg>\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tGovernment\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\"><path d=\"M0 0 C3.1875 1.5 3.1875 1.5 5 3 C5.61875 2.505 6.2375 2.01 6.875 1.5 C11.29155566 -0.61994672 15.18397319 -0.82450379 20 0 C23.48691814 1.732763 25.52919529 4.12259122 27.375 7.5625 C28 10 28 10 28 14 C29.98 14 31.96 14 34 14 C34 14.99 34 15.98 34 17 C31.69 17 29.38 17 27 17 C26.92724854 17.72469482 26.85449707 18.44938965 26.77954102 19.19604492 C25.78251758 22.78226922 24.18324006 24.27419994 21.52734375 26.86328125 C20.62822266 27.74951172 19.72910156 28.63574219 18.80273438 29.54882812 C17.85720703 30.46083984 16.91167969 31.37285156 15.9375 32.3125 C14.97760179 33.25232276 14.01860671 34.19306889 13.06054688 35.13476562 C10.71576088 37.43242024 8.36215473 39.7202276 6 42 C3.13369265 40.60556009 0.71476763 39.15790664 -1.75 37.125 C-2.36359375 36.63257813 -2.9771875 36.14015625 -3.609375 35.6328125 C-5 34 -5 34 -5 30 C-0.62140745 30.50522222 1.81651224 33.17827222 5 36 C15.14785334 27.97281132 15.14785334 27.97281132 23 18 C22.34 18 21.68 18 21 18 C19.36323743 19.9600281 19.36323743 19.9600281 18 22 C16.35 21.67 14.7 21.34 13 21 C12.34 21.99 11.68 22.98 11 24 C8 23 8 23 6.3125 19.9375 C5.879375 18.968125 5.44625 17.99875 5 17 C3.35 19.31 1.7 21.62 0 24 C-0.99 23.67 -1.98 23.34 -3 23 C-3.33 22.34 -3.66 21.68 -4 21 C-4.721875 21.268125 -5.44375 21.53625 -6.1875 21.8125 C-9 22 -9 22 -11.8125 19.5625 C-12.534375 18.716875 -13.25625 17.87125 -14 17 C-13.34 17.928125 -12.68 18.85625 -12 19.8125 C-10 23 -10 23 -10 26 C-11.75 25.875 -11.75 25.875 -14 25 C-18 19.77777778 -18 19.77777778 -18 17 C-20.31 17 -22.62 17 -25 17 C-25 16.01 -25 15.02 -25 14 C-22.69 14 -20.38 14 -18 14 C-18.0825 13.13375 -18.165 12.2675 -18.25 11.375 C-17.93918637 7.17901595 -16.59375096 5.26071549 -14 2 C-9.55299615 -0.96466923 -5.21871437 -0.52568072 0 0 Z M-14 8 C-14.96298724 11.17562802 -14.96298724 11.17562802 -15 14 C-13.576875 14.185625 -13.576875 14.185625 -12.125 14.375 C-9 15 -9 15 -7 17 C-5.35 16.01 -3.7 15.02 -2 14 C-1.67 14.99 -1.34 15.98 -1 17 C1.50037734 14.82575883 2.43628586 13.26954202 3 10 C6 11 6 11 7.6875 14.0625 C8.120625 15.031875 8.55375 16.00125 9 17 C9.66 17 10.32 17 11 17 C11.33 16.34 11.66 15.68 12 15 C12.99 14.67 13.98 14.34 15 14 C15.33 14.99 15.66 15.98 16 17 C16.66 16.67 17.32 16.34 18 16 C18 15.34 18 14.68 18 14 C19.98 14 21.96 14 24 14 C23.76435605 9.91550495 23.59037881 7.65785068 20.8125 4.5625 C17.43388366 2.68549092 15.81030177 2.37790992 12 3 C9.99384866 4.32405988 7.99330842 5.65668346 6 7 C3.20372964 6.91526453 1.9290542 5.95452192 -0.4375 4.4375 C-6.34444855 1.12384593 -9.53807588 3.33526115 -14 8 Z \" fill=\"#FFF6F6\" transform=\"translate(30,0)\"><\/path><path d=\"M0 0 C2.66015625 1.0390625 2.66015625 1.0390625 5.1875 2.25 C8.59517212 3.86262589 8.59517212 3.86262589 12.19140625 3.375 C13.54336542 2.63616842 14.87468776 1.85798946 16.1796875 1.0390625 C18.84810898 -0.48411371 21.01082161 -0.42702548 24 0 C26 2 26 2 26.58203125 4.765625 C25.8201654 8.99934934 24.22127462 9.9361971 20.81445312 12.33984375 C20.11255859 12.80519531 19.41066406 13.27054688 18.6875 13.75 C17.99720703 14.23082031 17.30691406 14.71164063 16.59570312 15.20703125 C14.74333562 16.49205528 12.87748755 17.75207793 11 19 C10.01 19.66 9.02 20.32 8 21 C-0.27797843 22.39863683 -8.22181129 19.51053929 -16 17 C-16.33 17.99 -16.66 18.98 -17 20 C-18.64574566 20.02688151 -20.29161413 20.04634123 -21.9375 20.0625 C-22.85402344 20.07410156 -23.77054688 20.08570312 -24.71484375 20.09765625 C-27 20 -27 20 -28 19 C-28.09986975 16.15664952 -28.13877881 13.34302837 -28.125 10.5 C-28.12886719 9.70207031 -28.13273437 8.90414062 -28.13671875 8.08203125 C-28.12660767 2.12660767 -28.12660767 2.12660767 -27 1 C-25.35659133 0.90145345 -23.7088539 0.87027589 -22.0625 0.875 C-21.16660156 0.87242188 -20.27070313 0.86984375 -19.34765625 0.8671875 C-17 1 -17 1 -15 2 C-14.10667969 1.54753906 -14.10667969 1.54753906 -13.1953125 1.0859375 C-9.05681068 -0.96122176 -4.49923401 -0.53775705 0 0 Z M-16 6 C-16 8.64 -16 11.28 -16 14 C-13.8131784 14.48225331 -11.62550745 14.96065583 -9.4375 15.4375 C-8.21933594 15.70433594 -7.00117188 15.97117187 -5.74609375 16.24609375 C-4.50988281 16.49488281 -3.27367187 16.74367188 -2 17 C-0.80503906 17.26039062 0.38992187 17.52078125 1.62109375 17.7890625 C5.70765999 18.04417762 7.1706793 17.24354419 10.5 14.9375 C11.43457031 14.29554687 12.36914062 13.65359375 13.33203125 12.9921875 C16.71103885 10.46906323 19.88280995 7.84010649 23 5 C22.34 4.34 21.68 3.68 21 3 C18.85299207 4.14367738 16.70737007 5.28982607 14.5625 6.4375 C13.95083984 6.76298828 13.33917969 7.08847656 12.70898438 7.42382812 C9.66283794 8.93715142 9.66283794 8.93715142 7 11 C2.52519101 11.17548271 -1.60833973 10.85690932 -6 10 C-6 9.01 -6 8.02 -6 7 C-2.37 7.66 1.26 8.32 5 9 C4.67 7.68 4.34 6.36 4 5 C-4.17579188 2.43504568 -8.22252005 2.83627934 -16 6 Z M-25 4 C-25 8.29 -25 12.58 -25 17 C-23.02 17 -21.04 17 -19 17 C-19 12.71 -19 8.42 -19 4 C-20.98 4 -22.96 4 -25 4 Z \" fill=\"#FFF6F6\" transform=\"translate(28,43)\"><\/path><path d=\"M0 0 C0.99 0 1.98 0 3 0 C3 1.32 3 2.64 3 4 C2.01 4 1.02 4 0 4 C0 2.68 0 1.36 0 0 Z \" fill=\"#FFF8F8\" transform=\"translate(21,26)\"><\/path><\/svg>\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tHealth and Wellness\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\"><path d=\"M0 0 C3.3125 2 3.3125 2 6 4 C9.12498166 4.3373846 9.12498166 4.3373846 11.1875 2 C14.25850931 -0.18382884 16.24744367 -0.59264959 20.00390625 -0.38671875 C23.38042876 0.26744119 25.45175467 1.75511721 28 4 C30.31691163 7.62647038 30.28119746 10.93390961 29.59375 15.06640625 C28.54368417 18.48602854 26.88527768 19.97416673 24 22 C19.78356434 23.39680276 16.87899705 23.35497958 12.75 21.6875 C11.8425 21.130625 10.935 20.57375 10 20 C9.21625 19.608125 8.4325 19.21625 7.625 18.8125 C7.08875 18.544375 6.5525 18.27625 6 18 C5.21625 18.639375 4.4325 19.27875 3.625 19.9375 C-0.17367482 22.92217308 -2.15772359 23.4656035 -7 23 C-10.6578218 20.96006092 -12.66946174 19.49580738 -15 16 C-15.68343706 12.22311096 -15.85107095 8.52813111 -13.94921875 5.11328125 C-9.88394255 0.16059963 -6.27613615 -0.89993014 0 0 Z M-11.875 6.75 C-13.59594712 10.19189423 -13.03958743 12.361444 -12 16 C-9.50308805 18.78227332 -7.80714078 19.80269892 -4.1875 20.6875 C1.48585394 19.46383542 5.02126488 14.95981796 9.04296875 10.9765625 C14.16601722 6.12106202 14.16601722 6.12106202 18.875 5.4375 C22 6 22 6 24 8 C24.33015665 11.10347254 24.50531294 13.15781176 22.875 15.875 C20.06181421 17.56291147 18.22507435 17.45151041 15 17 C12.125 15 12.125 15 10 13 C9.65699357 16.13728919 9.65699357 16.13728919 12.0625 18.1875 C15.73396914 20.45287458 17.75368609 20.61764566 22 20 C25.30748965 17.38882396 26.81680509 15.37396185 27.375 11.1875 C27.25902016 7.83246151 27.25902016 7.83246151 24.8125 5.1875 C21.94061626 2.95381265 20.61181438 2 17 2 C12.70859144 4.14206132 9.59198828 7.19826939 6.3125 10.625 C0.29073187 16.8626881 0.29073187 16.8626881 -3.9375 17.3125 C-7 17 -7 17 -8.9375 15.375 C-10.35168205 12.21388719 -9.87877792 10.29541719 -9 7 C-8 6 -8 6 -4.125 5.75 C-0.27815315 5.77747748 -0.27815315 5.77747748 1.875 7.5 C2.24625 7.995 2.6175 8.49 3 9 C3.66 9 4.32 9 5 9 C3.89184175 5.78634109 3.01470446 5.0085776 0 3.25 C-5.22659822 1.07225074 -7.86992986 3.01193453 -11.875 6.75 Z M-8 9 C-7.81171228 11.44480079 -7.81171228 11.44480079 -7 14 C-5.03241727 15.36020151 -5.03241727 15.36020151 -3 16 C-1.35 14.35 0.3 12.7 2 11 C0.18777466 8.9375006 0.18777466 8.9375006 -2 7 C-5.18490007 6.7226499 -5.18490007 6.7226499 -8 9 Z M13 10 C14.04874998 12.62187494 14.64931313 13.79371361 17.125 15.25 C17.74375 15.4975 18.3625 15.745 19 16 C19.99 15.34 20.98 14.68 22 14 C22.41666667 11.5 22.41666667 11.5 22 9 C21.34 8.34 20.68 7.68 20 7 C16.48283697 7 15.62878252 7.82445585 13 10 Z \" fill=\"#FFF0F0\" transform=\"translate(31,4)\"><\/path><path d=\"M0 0 C2.0625 0.9375 2.0625 0.9375 2.8515625 2.99609375 C3.16042718 7.30304008 0.93112211 9.72495035 -1.5625 13 C-2.00207031 13.61166016 -2.44164062 14.22332031 -2.89453125 14.85351562 C-7.99261979 21.76807853 -7.99261979 21.76807853 -11.9375 23.9375 C-16.03907234 24.553494 -20.10753545 24.63423628 -24.25 24.6875 C-25.37212891 24.71714844 -26.49425781 24.74679688 -27.65039062 24.77734375 C-30.41283207 24.84787417 -33.17443774 24.90065493 -35.9375 24.9375 C-35.9375 25.9275 -35.9375 26.9175 -35.9375 27.9375 C-37.25 29.76171875 -37.25 29.76171875 -38.9375 31.625 C-39.494375 32.24761719 -40.05125 32.87023438 -40.625 33.51171875 C-41.058125 33.98222656 -41.49125 34.45273437 -41.9375 34.9375 C-45.08954981 33.54402624 -47.19921773 31.91264921 -49.609375 29.4609375 C-50.27324219 28.790625 -50.93710937 28.1203125 -51.62109375 27.4296875 C-52.30300781 26.73101562 -52.98492187 26.03234375 -53.6875 25.3125 C-54.38488281 24.60609375 -55.08226562 23.8996875 -55.80078125 23.171875 C-57.51762488 21.43151297 -59.22961832 19.68665019 -60.9375 17.9375 C-59.55689854 15.08817358 -58.47015215 12.90734056 -55.9375 10.9375 C-55.195 10.834375 -54.4525 10.73125 -53.6875 10.625 C-50.07579916 9.72207479 -48.18625868 7.80110003 -45.48828125 5.3125 C-42.54129577 2.69955569 -40.34261609 2.80229385 -36.5 2.8125 C-35.53191406 2.80992188 -34.56382813 2.80734375 -33.56640625 2.8046875 C-30.9375 2.9375 -30.9375 2.9375 -27.9375 3.9375 C-24.75341307 4.16339806 -21.57596659 4.33054559 -18.38671875 4.45507812 C-14.74895799 4.64521749 -13.04135071 4.86826619 -9.9375 6.9375 C-9.49019531 6.42058594 -9.04289062 5.90367188 -8.58203125 5.37109375 C-3.58243997 -0.07622213 -3.58243997 -0.07622213 0 0 Z M-3.5234375 4.328125 C-4.11382812 4.94171875 -4.70421875 5.5553125 -5.3125 6.1875 C-5.89773437 6.79078125 -6.48296875 7.3940625 -7.0859375 8.015625 C-8.98303232 9.92999955 -8.98303232 9.92999955 -10.7109375 12.125 C-13.82159775 14.65718659 -16.22651689 14.54079692 -20.1875 14.6875 C-21.45078125 14.74421875 -22.7140625 14.8009375 -24.015625 14.859375 C-25.46195313 14.89804687 -25.46195313 14.89804687 -26.9375 14.9375 C-26.9375 14.2775 -26.9375 13.6175 -26.9375 12.9375 C-26.09445313 12.94910156 -25.25140625 12.96070313 -24.3828125 12.97265625 C-23.28710938 12.98167969 -22.19140625 12.99070312 -21.0625 13 C-19.97195312 13.01160156 -18.88140625 13.02320313 -17.7578125 13.03515625 C-14.98572454 13.13494303 -14.98572454 13.13494303 -12.9375 11.9375 C-13.4325 9.9575 -13.4325 9.9575 -13.9375 7.9375 C-15.00871094 7.87691406 -16.07992187 7.81632812 -17.18359375 7.75390625 C-18.58074391 7.66951463 -19.97787857 7.58486594 -21.375 7.5 C-22.08205078 7.46068359 -22.78910156 7.42136719 -23.51757812 7.38085938 C-28.82421875 7.05078125 -28.82421875 7.05078125 -29.9375 5.9375 C-35.07240878 5.21450484 -39.96622046 4.74097221 -44.51171875 7.5 C-46.45189785 9.22769988 -48.23606031 10.97584012 -49.9375 12.9375 C-48.52905282 16.15274305 -46.83405214 18.25933868 -44.3125 20.6875 C-43.68085937 21.30109375 -43.04921875 21.9146875 -42.3984375 22.546875 C-41.91632812 23.00578125 -41.43421875 23.4646875 -40.9375 23.9375 C-39.9475 23.6075 -38.9575 23.2775 -37.9375 22.9375 C-36.22369674 22.82357564 -34.5063325 22.75948817 -32.7890625 22.7265625 C-31.78359375 22.69820312 -30.778125 22.66984375 -29.7421875 22.640625 C-27.63038172 22.58873788 -25.51837609 22.54440874 -23.40625 22.5078125 C-16.10547203 22.43678572 -16.10547203 22.43678572 -9.9375 18.9375 C-8.02741856 16.86514742 -6.31286545 14.69298835 -4.625 12.4375 C-4.17060547 11.85613281 -3.71621094 11.27476563 -3.24804688 10.67578125 C-0.53623801 7.20555532 -0.53623801 7.20555532 0.0625 2.9375 C-2.0384163 2.71773636 -2.0384163 2.71773636 -3.5234375 4.328125 Z M-54.9375 13.9375 C-55.5975 15.2575 -56.2575 16.5775 -56.9375 17.9375 C-52.6475 22.2275 -48.3575 26.5175 -43.9375 30.9375 C-42.6175 30.2775 -41.2975 29.6175 -39.9375 28.9375 C-44.32918507 23.66747792 -48.8801379 18.58447949 -53.9375 13.9375 C-54.2675 13.9375 -54.5975 13.9375 -54.9375 13.9375 Z \" fill=\"#FFEFEF\" transform=\"translate(60.9375,25.0625)\"><\/path><\/svg>\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tHospitality\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\"><path d=\"M0 0 C7.59 0 15.18 0 23 0 C23 0.99 23 1.98 23 3 C23.78246094 2.98839844 24.56492188 2.97679687 25.37109375 2.96484375 C26.38300781 2.95582031 27.39492188 2.94679687 28.4375 2.9375 C29.44683594 2.92589844 30.45617188 2.91429687 31.49609375 2.90234375 C34 3 34 3 35 4 C35.07205511 5.68608966 35.08386068 7.37500659 35.0625 9.0625 C35.05347656 9.98160156 35.04445312 10.90070312 35.03515625 11.84765625 C35.02355469 12.55792969 35.01195312 13.26820312 35 14 C36.134375 14.103125 37.26875 14.20625 38.4375 14.3125 C41.72279422 14.71152507 44.65841209 15.46208314 47.78515625 16.54296875 C48.57929932 16.81520264 49.37344238 17.08743652 50.19165039 17.36791992 C50.78840576 17.57650635 51.38516113 17.78509277 52 18 C52.14700056 21.16616599 52.23462106 24.33143982 52.3125 27.5 C52.35439453 28.386875 52.39628906 29.27375 52.43945312 30.1875 C52.55845098 36.6609835 51.31984598 41.07234021 47 46 C43.92126931 48.49022134 41.07078064 49.90886973 37.0625 50.25 C36.381875 50.1675 35.70125 50.085 35 50 C35.144375 51.010625 35.28875 52.02125 35.4375 53.0625 C34.92236813 57.69868681 33.98717898 59.55235201 30.62109375 62.6875 C24.95476366 65.52488735 18.15992748 64.46587687 12 64 C12 63.01 12 62.02 12 61 C15.96 61 19.92 61 24 61 C24 59.02 24 57.04 24 55 C26 53 26 53 29.125 52.875 C30.07375 52.91625 31.0225 52.9575 32 53 C31.61431269 50.5555764 31.33590575 49.30576036 29.4765625 47.61328125 C28.86554687 47.18402344 28.25453125 46.75476562 27.625 46.3125 C23.26857154 42.83272449 22.36871227 39.3138241 21 34 C17.37 34 13.74 34 10 34 C10 33.01 10 32.02 10 31 C13.63 31 17.26 31 21 31 C21 27.37 21 23.74 21 20 C17.37 20 13.74 20 10 20 C10 19.01 10 18.02 10 17 C11.18078125 16.93941406 12.3615625 16.87882812 13.578125 16.81640625 C15.1354277 16.73197418 16.69271879 16.64732751 18.25 16.5625 C19.41595703 16.50352539 19.41595703 16.50352539 20.60546875 16.44335938 C21.35957031 16.40146484 22.11367188 16.35957031 22.890625 16.31640625 C23.58188477 16.27974854 24.27314453 16.24309082 24.98535156 16.20532227 C27.35620639 16.0121859 27.35620639 16.0121859 31 15 C31.33 12.03 31.66 9.06 32 6 C29.03 6 26.06 6 23 6 C22.34 7.32 21.68 8.64 21 10 C14.73 10 8.46 10 2 10 C1.34 8.68 0.68 7.36 0 6 C-2.97 6 -5.94 6 -9 6 C-9 24.15 -9 42.3 -9 61 C-4.71 61 -0.42 61 4 61 C4 61.99 4 62.98 4 64 C1.52076199 64.02685095 -0.9581884 64.04676547 -3.4375 64.0625 C-4.14455078 64.07087891 -4.85160156 64.07925781 -5.58007812 64.08789062 C-7.38693559 64.09653588 -9.19387603 64.05220011 -11 64 C-12.74299388 62.25700612 -12.12758682 59.85593748 -12.12939453 57.48632812 C-12.13254669 56.30840698 -12.13569885 55.13048584 -12.13894653 53.91687012 C-12.1369223 52.63461548 -12.13489807 51.35236084 -12.1328125 50.03125 C-12.13376923 48.72546997 -12.13472595 47.41968994 -12.13571167 46.07434082 C-12.13718833 43.30687278 -12.13503511 40.53943696 -12.13037109 37.77197266 C-12.12467381 34.21737351 -12.12795298 30.66284986 -12.13394356 27.10825348 C-12.13841747 23.72841286 -12.13528886 20.34859277 -12.1328125 16.96875 C-12.13483673 15.68649536 -12.13686096 14.40424072 -12.13894653 13.08312988 C-12.13579437 11.90520874 -12.13264221 10.7272876 -12.12939453 9.51367188 C-12.12859894 8.47078003 -12.12780334 7.42788818 -12.12698364 6.35339355 C-12 4 -12 4 -11 3 C-9.14712498 2.92773498 -7.29166122 2.9161878 -5.4375 2.9375 C-4.42558594 2.94652344 -3.41367188 2.95554688 -2.37109375 2.96484375 C-1.19740234 2.98224609 -1.19740234 2.98224609 0 3 C0 2.01 0 1.02 0 0 Z M4 3 C4 4.32 4 5.64 4 7 C8.95 7 13.9 7 19 7 C19 5.68 19 4.36 19 3 C14.05 3 9.1 3 4 3 Z M24 21 C23.72312248 28.50645718 23.71151587 35.18585979 27.6875 41.8125 C30.66037277 44.62467694 33.0496114 45.91023763 37 47 C42.27241308 45.41827608 44.86196779 42.30358703 48 38 C49.18681726 34.43954823 49.09689832 31.56191663 49.0625 27.8125 C49.05347656 26.54019531 49.04445313 25.26789062 49.03515625 23.95703125 C49.02355469 22.98121094 49.01195313 22.00539063 49 21 C39.70406079 17.45868982 33.29593921 17.45868982 24 21 Z \" fill=\"#FFFEFE\" transform=\"translate(12,0)\"><\/path><path d=\"M0 0 C0.08139142 2.39652528 0.14067009 4.79025436 0.1875 7.1875 C0.21263672 7.86103516 0.23777344 8.53457031 0.26367188 9.22851562 C0.32933376 13.71541119 -0.2677535 16.42907832 -3 20 C-6.01757067 22.51464223 -7.54477949 22.99187106 -11.5 23.0625 C-16.17595974 21.64301222 -17.27970302 20.00043674 -20 16 C-21.14077657 12.57767028 -21.09815117 9.91326783 -21.0625 6.3125 C-21.05347656 5.13300781 -21.04445312 3.95351563 -21.03515625 2.73828125 C-21.02355469 1.83464844 -21.01195312 0.93101563 -21 0 C-13.11453138 -3.16491598 -7.96046293 -3.28978315 0 0 Z M-18 3 C-17.90386242 10.56420908 -17.90386242 10.56420908 -14.75 17.25 C-12.17416497 19.23488303 -12.17416497 19.23488303 -9.375 19 C-6.88799346 17.95283935 -5.6364318 17.12736134 -4 15 C-3.03929566 12.11788698 -2.89418117 10.30149956 -2.9375 7.3125 C-2.94652344 6.50425781 -2.95554687 5.69601563 -2.96484375 4.86328125 C-2.97644531 4.24839844 -2.98804688 3.63351563 -3 3 C-8.78250849 0.35656755 -12.21768617 0.57142819 -18 3 Z \" fill=\"#FFFEFE\" transform=\"translate(59,22)\"><\/path><path d=\"M0 0 C4.62 0 9.24 0 14 0 C14 1.32 14 2.64 14 4 C9.38 4 4.76 4 0 4 C0 2.68 0 1.36 0 0 Z \" fill=\"#FFFEFE\" transform=\"translate(22,44)\"><\/path><path d=\"M0 0 C1.32 0 2.64 0 4 0 C3.61094382 2.72339328 2.93262433 4.08903214 1.25 6.3125 C-1 8 -1 8 -3.75 7.75 C-4.4925 7.5025 -5.235 7.255 -6 7 C-6.33 5.68 -6.66 4.36 -7 3 C-5.5459375 2.5359375 -5.5459375 2.5359375 -4.0625 2.0625 C-1.15934208 1.30476658 -1.15934208 1.30476658 0 0 Z \" fill=\"#FFFEFE\" transform=\"translate(15,45)\"><\/path><path d=\"M0 0 C0.99 0.33 1.98 0.66 3 1 C1.56036361 4.35915158 -0.12416589 6.71624938 -3 9 C-5.25 8.75 -5.25 8.75 -7 8 C-7.33 6.35 -7.66 4.7 -8 3 C-6.8553125 3.0928125 -6.8553125 3.0928125 -5.6875 3.1875 C-2.95474688 3.25898085 -2.95474688 3.25898085 -1.1875 1.5 C-0.795625 1.005 -0.40375 0.51 0 0 Z \" fill=\"#FFFEFE\" transform=\"translate(16,17)\"><\/path><path d=\"M0 0 C0.99 0 1.98 0 3 0 C2.52797514 4.24822374 0.03344482 6.19989709 -3 9 C-4.9375 8.25 -4.9375 8.25 -7 7 C-7.75 4.875 -7.75 4.875 -8 3 C-6.8553125 3.0928125 -6.8553125 3.0928125 -5.6875 3.1875 C-2.49347163 2.96466081 -2.0779007 2.26680076 0 0 Z \" fill=\"#FFFEFE\" transform=\"translate(16,31)\"><\/path><path d=\"M0 0 C0.99 0 1.98 0 3 0 C2.46104623 3.7726764 1.00464642 5.68212991 -2 8 C-5.01811422 7.82246387 -5.83735215 7.16264785 -8 5 C-8 4.01 -8 3.02 -8 2 C-6.8553125 2.3403125 -6.8553125 2.3403125 -5.6875 2.6875 C-4.800625 2.790625 -3.91375 2.89375 -3 3 C-1.35405861 1.60411246 -1.35405861 1.60411246 0 0 Z \" fill=\"#FFFEFE\" transform=\"translate(51,28)\"><\/path><path d=\"M0 0 C3.96 0 7.92 0 12 0 C12 0.99 12 1.98 12 3 C8.04 3 4.08 3 0 3 C0 2.01 0 1.02 0 0 Z \" fill=\"#FFFEFE\" transform=\"translate(22,50)\"><\/path><path d=\"M0 0 C2.97 0 5.94 0 9 0 C8.67 1.32 8.34 2.64 8 4 C5.69 4 3.38 4 1 4 C0.67 2.68 0.34 1.36 0 0 Z \" fill=\"#FFFEFE\" transform=\"translate(22,36)\"><\/path><path d=\"M0 0 C2.31 0 4.62 0 7 0 C7 1.32 7 2.64 7 4 C4.36 4 1.72 4 -1 4 C-0.67 2.68 -0.34 1.36 0 0 Z \" fill=\"#FFFEFE\" transform=\"translate(23,22)\"><\/path><path d=\"M0 0 C1.32 0.33 2.64 0.66 4 1 C3.67 1.66 3.34 2.32 3 3 C2.01 3 1.02 3 0 3 C0 2.01 0 1.02 0 0 Z \" fill=\"#FFFEFE\" transform=\"translate(18,61)\"><\/path><\/svg>\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tInsurance\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\"><path d=\"M0 0 C3.28160389 1.16080615 4.81703208 2.76144029 7.1796875 5.30078125 C10.3251048 8.65627 10.3251048 8.65627 13.89453125 11.52734375 C14.46300781 11.98882812 15.03148437 12.4503125 15.6171875 12.92578125 C15.6171875 13.91578125 15.6171875 14.90578125 15.6171875 15.92578125 C11.57043134 15.40154238 9.84068694 13.40298527 7.1171875 10.48828125 C4.43259554 7.62441004 2.26579933 5.44327208 -1.3828125 3.92578125 C-1.9396875 4.49425781 -2.4965625 5.06273437 -3.0703125 5.6484375 C-6.83988896 9.46258666 -10.61412805 13.19409282 -14.6953125 16.67578125 C-17.636035 19.19388494 -20.09480078 21.77976513 -22.3828125 24.92578125 C-21.898125 24.42949219 -21.4134375 23.93320312 -20.9140625 23.421875 C-16.79765466 19.25005398 -12.59511379 15.2725847 -8.1328125 11.47265625 C-6.22321883 9.84387306 -6.22321883 9.84387306 -4.1328125 7.42578125 C-3.5553125 6.93078125 -2.9778125 6.43578125 -2.3828125 5.92578125 C1.02475359 6.31623153 2.86948109 7.72279961 5.3671875 9.98828125 C6.058125 10.6121875 6.7490625 11.23609375 7.4609375 11.87890625 C10.30935337 14.58283725 13.05165234 17.38062133 15.7578125 20.2265625 C17.62027014 21.92859837 19.31529132 22.92252119 21.6171875 23.92578125 C20.9571875 23.32765625 20.2971875 22.72953125 19.6171875 22.11328125 C17.6171875 19.92578125 17.6171875 19.92578125 17.6171875 16.92578125 C20.9892924 18.37096906 23.31599113 20.04928578 25.6171875 22.92578125 C25.9296875 25.61328125 25.9296875 25.61328125 25.6171875 27.92578125 C24.6171875 28.92578125 24.6171875 28.92578125 22.1171875 29.05078125 C19.6171875 28.92578125 19.6171875 28.92578125 18.6171875 27.92578125 C18.6171875 31.88578125 18.6171875 35.84578125 18.6171875 39.92578125 C19.4834375 39.26578125 20.3496875 38.60578125 21.2421875 37.92578125 C24.83691561 35.795572 26.5337167 35.45095906 30.6171875 35.92578125 C31.6171875 36.92578125 31.6171875 36.92578125 32.05078125 39.6015625 C31.43677139 44.30897139 29.15790982 46.08461856 25.6796875 49.11328125 C25.08212646 49.64356934 24.48456543 50.17385742 23.86889648 50.72021484 C19.37145702 54.57066699 15.54159482 57.0107056 9.6171875 57.92578125 C7.90789063 58.22162109 7.90789063 58.22162109 6.1640625 58.5234375 C-3.10688433 59.98778161 -9.46797146 60.67958399 -18.015625 56.60546875 C-20.36474904 55.66336688 -20.36474904 55.66336688 -22.45703125 56.796875 C-23.09253906 57.16941406 -23.72804688 57.54195312 -24.3828125 57.92578125 C-28.0703125 58.11328125 -28.0703125 58.11328125 -31.3828125 57.92578125 C-32.3828125 56.92578125 -32.3828125 56.92578125 -32.4453125 53.86328125 C-32.4246875 52.89390625 -32.4040625 51.92453125 -32.3828125 50.92578125 C-31.7228125 50.92578125 -31.0628125 50.92578125 -30.3828125 50.92578125 C-30.0528125 51.91578125 -29.7228125 52.90578125 -29.3828125 53.92578125 C-28.0628125 54.25578125 -26.7428125 54.58578125 -25.3828125 54.92578125 C-25.7128125 47.33578125 -26.0428125 39.74578125 -26.3828125 31.92578125 C-27.3728125 31.92578125 -28.3628125 31.92578125 -29.3828125 31.92578125 C-29.7128125 37.20578125 -30.0428125 42.48578125 -30.3828125 47.92578125 C-31.0428125 47.92578125 -31.7028125 47.92578125 -32.3828125 47.92578125 C-32.40965237 44.94655532 -32.42957287 41.9675683 -32.4453125 38.98828125 C-32.45369141 38.13814453 -32.46207031 37.28800781 -32.47070312 36.41210938 C-32.47392578 35.60322266 -32.47714844 34.79433594 -32.48046875 33.9609375 C-32.48570557 33.21207275 -32.49094238 32.46320801 -32.49633789 31.69165039 C-32.3828125 29.92578125 -32.3828125 29.92578125 -31.3828125 28.92578125 C-29.71664135 28.88514293 -28.04893155 28.88306025 -26.3828125 28.92578125 C-26.6509375 28.20390625 -26.9190625 27.48203125 -27.1953125 26.73828125 C-27.3828125 23.92578125 -27.3828125 23.92578125 -25.1328125 21.30078125 C-23.69178018 20.05625334 -22.24524815 18.81658748 -20.75390625 17.6328125 C-18.82377297 15.22976907 -18.87432148 13.28143396 -18.6953125 10.23828125 C-18.62957031 9.24441406 -18.56382813 8.25054687 -18.49609375 7.2265625 C-18.45871094 6.46730469 -18.42132813 5.70804687 -18.3828125 4.92578125 C-17.73054688 4.98378906 -17.07828125 5.04179688 -16.40625 5.1015625 C-11.25421833 5.50966568 -11.25421833 5.50966568 -6.55859375 3.77734375 C-6.06746094 3.31070312 -5.57632812 2.8440625 -5.0703125 2.36328125 C-2.3828125 -0.07421875 -2.3828125 -0.07421875 0 0 Z M-16.3828125 7.92578125 C-16.3828125 9.57578125 -16.3828125 11.22578125 -16.3828125 12.92578125 C-14.3428406 11.56254382 -14.3428406 11.56254382 -12.3828125 9.92578125 C-12.3828125 9.26578125 -12.3828125 8.60578125 -12.3828125 7.92578125 C-13.7028125 7.92578125 -15.0228125 7.92578125 -16.3828125 7.92578125 Z M-9.5703125 16.36328125 C-10.22451172 16.95560547 -10.87871094 17.54792969 -11.55273438 18.15820312 C-15.19757433 21.70427319 -15.19757433 21.70427319 -16.80712891 26.40673828 C-16.85265205 29.16042046 -16.85265205 29.16042046 -16.3828125 32.92578125 C-11.9278125 34.90578125 -11.9278125 34.90578125 -7.3828125 36.92578125 C-7.0528125 33.29578125 -6.7228125 29.66578125 -6.3828125 25.92578125 C-0.4428125 25.43078125 -0.4428125 25.43078125 5.6171875 24.92578125 C5.6171875 29.54578125 5.6171875 34.16578125 5.6171875 38.92578125 C6.9371875 39.25578125 8.2571875 39.58578125 9.6171875 39.92578125 C9.9471875 41.57578125 10.2771875 43.22578125 10.6171875 44.92578125 C12.5971875 44.43078125 12.5971875 44.43078125 14.6171875 43.92578125 C16.39179709 31.94635144 16.39179709 31.94635144 13.29150391 20.65527344 C9.66207247 16.31004622 5.39773487 12.92544951 0.6171875 9.92578125 C-4.13311828 9.92578125 -6.29653377 13.16830963 -9.5703125 16.36328125 Z M-21.9453125 28.42578125 C-22.4196875 28.92078125 -22.8940625 29.41578125 -23.3828125 29.92578125 C-23.0528125 30.91578125 -22.7228125 31.90578125 -22.3828125 32.92578125 C-21.3928125 32.92578125 -20.4028125 32.92578125 -19.3828125 32.92578125 C-19.3828125 30.94578125 -19.3828125 28.96578125 -19.3828125 26.92578125 C-20.62357552 26.81035928 -20.62357552 26.81035928 -21.9453125 28.42578125 Z M-4.3828125 27.92578125 C-4.40970466 29.40485017 -4.42915871 30.88405608 -4.4453125 32.36328125 C-4.45691406 33.18699219 -4.46851562 34.01070312 -4.48046875 34.859375 C-4.61548598 36.91742063 -4.61548598 36.91742063 -3.3828125 37.92578125 C-1.38322886 37.96658908 0.61764004 37.96832481 2.6171875 37.92578125 C2.6171875 34.62578125 2.6171875 31.32578125 2.6171875 27.92578125 C0.3071875 27.92578125 -2.0028125 27.92578125 -4.3828125 27.92578125 Z M-22.3828125 34.92578125 C-22.3828125 40.53578125 -22.3828125 46.14578125 -22.3828125 51.92578125 C-13.17053569 56.03125244 -7.25910393 57.55231146 2.6171875 55.92578125 C4.10025391 55.85423828 4.10025391 55.85423828 5.61328125 55.78125 C14.18300033 55.1237553 18.44945079 51.25640052 24.21875 45.359375 C26.6171875 42.92578125 26.6171875 42.92578125 28.6171875 41.92578125 C28.6171875 40.93578125 28.6171875 39.94578125 28.6171875 38.92578125 C25.19324374 39.5255408 23.44545264 40.78503933 20.8046875 42.98828125 C14.47800642 47.3307323 7.99246615 46.45205742 0.6171875 45.92578125 C-0.65511719 45.84457031 -1.92742188 45.76335938 -3.23828125 45.6796875 C-6.29094171 45.46330481 -9.3361717 45.213491 -12.3828125 44.92578125 C-12.3828125 44.26578125 -12.3828125 43.60578125 -12.3828125 42.92578125 C-11.69316406 42.99796875 -11.00351562 43.07015625 -10.29296875 43.14453125 C-4.28692591 43.73772067 1.5828875 44.0247042 7.6171875 43.92578125 C5.3298626 40.77085035 2.7926924 40.35935814 -0.9309082 39.74731445 C-1.63691162 39.6412085 -2.34291504 39.53510254 -3.0703125 39.42578125 C-8.84759821 38.46516438 -13.94911318 37.16318685 -19.3828125 34.92578125 C-20.3728125 34.92578125 -21.3628125 34.92578125 -22.3828125 34.92578125 Z \" fill=\"#FFFFFF\" transform=\"translate(32.3828125,2.07421875)\"><\/path><\/svg>\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tReal Estate\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tTech and Software\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"deensimc-text-wrapper\">\n\t\t\t\t\t\t\t\t<p class=\"deensimc-scroll-text\">\n\t\t\t\t\tSemi-Government Companies\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ed1d1a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ed1d1a\" data-element_type=\"section\" id=\"case-study\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ad41eb\" data-id=\"6ad41eb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2f2d86f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f2d86f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-39ecc8f\" data-id=\"39ecc8f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e10b55e elementor-widget elementor-widget-heading\" data-id=\"e10b55e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Case Study<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c88fee2 elementor-widget elementor-widget-heading\" data-id=\"c88fee2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">A Showcase of Creativity\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4bef52c\" data-id=\"4bef52c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9fa3243 elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9fa3243\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3d21a3d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d21a3d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4a5a2dd\" data-id=\"4a5a2dd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a575eea elementor-widget elementor-widget-image\" data-id=\"a575eea\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"781\" height=\"717\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/case-study-new.png\" class=\"attachment-full size-full wp-image-5442\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/case-study-new.png 781w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/case-study-new-300x275.png 300w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/case-study-new-768x705.png 768w\" sizes=\"(max-width: 781px) 100vw, 781px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0bb9e32\" data-id=\"0bb9e32\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f94f884 elementor-widget elementor-widget-text-editor\" data-id=\"f94f884\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>From live client campaigns to conceptual explorations, this space captures the breadth of our thinking. Every project reflects our passion for bold ideas, sharp storytelling, and design that resonates.<\/p><p>As we continue to grow, so will this collection offering a deeper look into the kind of work that excites us and the kind of impact we aim to create.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5eabab elementor-widget elementor-widget-text-editor\" data-id=\"e5eabab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tFrom purpose-driven ideas to bold explorations, see how we bring creativity to life.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e6f291 elementor-widget elementor-widget-text-editor\" data-id=\"2e6f291\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tFor detailed Case Study Download\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2665ed8 elementor-icon-list--layout-inline elementor-align-left elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2665ed8\" data-element_type=\"widget\" id=\"download_pdf\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.angleadvt.com\/leo9\/Case-Study.pdf\" target=\"_blank\" rel=\"nofollow\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-pdf\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M369.9 97.9L286 14C277 5 264.8-.1 252.1-.1H48C21.5 0 0 21.5 0 48v416c0 26.5 21.5 48 48 48h288c26.5 0 48-21.5 48-48V131.9c0-12.7-5.1-25-14.1-34zM332.1 128H256V51.9l76.1 76.1zM48 464V48h160v104c0 13.3 10.7 24 24 24h104v288H48zm250.2-143.7c-12.2-12-47-8.7-64.4-6.5-17.2-10.5-28.7-25-36.8-46.3 3.9-16.1 10.1-40.6 5.4-56-4.2-26.2-37.8-23.6-42.6-5.9-4.4 16.1-.4 38.5 7 67.1-10 23.9-24.9 56-35.4 74.4-20 10.3-47 26.2-51 46.2-3.3 15.8 26 55.2 76.1-31.2 22.4-7.4 46.8-16.5 68.4-20.1 18.9 10.2 41 17 55.8 17 25.5 0 28-28.2 17.5-38.7zm-198.1 77.8c5.1-13.7 24.5-29.5 30.4-35-19 30.3-30.4 35.7-30.4 35zm81.6-190.6c7.4 0 6.7 32.1 1.8 40.8-4.4-13.9-4.3-40.8-1.8-40.8zm-24.4 136.6c9.7-16.9 18-37 24.7-54.7 8.3 15.1 18.9 27.2 30.1 35.5-20.8 4.3-38.9 13.1-54.8 19.2zm131.6-5s-5 6-37.3-7.8c35.1-2.6 40.9 5.4 37.3 7.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Positioning Maharashtra for Taiwanese Investment<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.angleadvt.com\/leo9\/Rebrand-Case-Study.pdf\" target=\"_blank\" rel=\"nofollow\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-pdf\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M369.9 97.9L286 14C277 5 264.8-.1 252.1-.1H48C21.5 0 0 21.5 0 48v416c0 26.5 21.5 48 48 48h288c26.5 0 48-21.5 48-48V131.9c0-12.7-5.1-25-14.1-34zM332.1 128H256V51.9l76.1 76.1zM48 464V48h160v104c0 13.3 10.7 24 24 24h104v288H48zm250.2-143.7c-12.2-12-47-8.7-64.4-6.5-17.2-10.5-28.7-25-36.8-46.3 3.9-16.1 10.1-40.6 5.4-56-4.2-26.2-37.8-23.6-42.6-5.9-4.4 16.1-.4 38.5 7 67.1-10 23.9-24.9 56-35.4 74.4-20 10.3-47 26.2-51 46.2-3.3 15.8 26 55.2 76.1-31.2 22.4-7.4 46.8-16.5 68.4-20.1 18.9 10.2 41 17 55.8 17 25.5 0 28-28.2 17.5-38.7zm-198.1 77.8c5.1-13.7 24.5-29.5 30.4-35-19 30.3-30.4 35.7-30.4 35zm81.6-190.6c7.4 0 6.7 32.1 1.8 40.8-4.4-13.9-4.3-40.8-1.8-40.8zm-24.4 136.6c9.7-16.9 18-37 24.7-54.7 8.3 15.1 18.9 27.2 30.1 35.5-20.8 4.3-38.9 13.1-54.8 19.2zm131.6-5s-5 6-37.3-7.8c35.1-2.6 40.9 5.4 37.3 7.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Our Take on Darjeeling Express<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8025d0d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8025d0d\" data-element_type=\"section\" id=\"services\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e1e1136\" data-id=\"e1e1136\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09eeea7 elementor-widget elementor-widget-heading\" data-id=\"09eeea7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Services<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c6062b3 services_item elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c6062b3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-af217b5\" data-id=\"af217b5\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3082965 elementor-widget elementor-widget-icon-box\" data-id=\"3082965\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#\" >\n\t\t\t\t\t\t\tBrand Strategy and Design\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDeveloping brands with purpose, strategy, and impact.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c9f0129\" data-id=\"c9f0129\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1951859 elementor-widget elementor-widget-icon-box\" data-id=\"1951859\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#\" >\n\t\t\t\t\t\t\tCampaign and Content Creation\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tCreative storytelling across platforms, grounded in culture and built to connect.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-29f11d4\" data-id=\"29f11d4\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e885a73 elementor-widget elementor-widget-icon-box\" data-id=\"e885a73\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#\" >\n\t\t\t\t\t\t\tDigital and Social Media Strategy\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAudience-first strategies designed for an ever-evolving digital world.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-108a433 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"108a433\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0ef24f8\" data-id=\"0ef24f8\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49e7b6a elementor-widget elementor-widget-icon-box\" data-id=\"49e7b6a\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#\" >\n\t\t\t\t\t\t\tEvent Management\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSeamless, end-to-end event execution designed to create real brand moments.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a5ca1bc\" data-id=\"a5ca1bc\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75fc793 elementor-widget elementor-widget-icon-box\" data-id=\"75fc793\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#\" >\n\t\t\t\t\t\t\tMedia Planning and Buying\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSmart media decisions that drive reach.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bc0bdad\" data-id=\"bc0bdad\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b8dc1e elementor-widget elementor-widget-icon-box\" data-id=\"3b8dc1e\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#\" >\n\t\t\t\t\t\t\tAccount Management\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tProviding consistent oversight to ensure brand alignment.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-04ce457 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"04ce457\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-45543f4\" data-id=\"45543f4\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3eea80f elementor-widget elementor-widget-icon-box\" data-id=\"3eea80f\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#\" >\n\t\t\t\t\t\t\tAffiliate and Performance Marketing\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tGrowth through strategic partnerships and measurable outcomes.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-19d858c\" data-id=\"19d858c\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-801c294 elementor-widget elementor-widget-icon-box\" data-id=\"801c294\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#\" >\n\t\t\t\t\t\t\tInserts and Promotional Marketing\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBrand placements designed to drive action.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9d47120\" data-id=\"9d47120\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc62e94 elementor-widget elementor-widget-icon-box\" data-id=\"bc62e94\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#\" >\n\t\t\t\t\t\t\tInternational and UK Media Expertise\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMedia strategies rooted in local insight and global perspective.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e4f545 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e4f545\" data-element_type=\"section\" id=\"our-client\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-70c164d1\" data-id=\"70c164d1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3dd69004 elementor-widget elementor-widget-heading\" data-id=\"3dd69004\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our Clients<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f193ab7 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"f193ab7\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-4880 gallery-columns-6 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"01\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTEzMCwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMDEucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/01.png'><img decoding=\"async\" width=\"418\" height=\"286\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/01.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/01.png 418w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/01-300x205.png 300w\" sizes=\"(max-width: 418px) 100vw, 418px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"02\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTEzMSwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMDIucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/02.png'><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"286\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/02.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/02.png 417w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/02-300x206.png 300w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"03\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE1MiwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMDMucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/03.png'><img loading=\"lazy\" decoding=\"async\" width=\"418\" height=\"286\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/03.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/03.png 418w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/03-300x205.png 300w\" sizes=\"(max-width: 418px) 100vw, 418px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"04\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTEzMiwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMDQucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/04.png'><img loading=\"lazy\" decoding=\"async\" width=\"418\" height=\"286\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/04.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/04.png 418w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/04-300x205.png 300w\" sizes=\"(max-width: 418px) 100vw, 418px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"09\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTEzMywidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMDkucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/09.png'><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"286\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/09.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/09.png 417w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/09-300x206.png 300w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"06\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE1MywidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMDYucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/06.png'><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"286\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/06.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/06.png 417w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/06-300x206.png 300w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"07\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE1NCwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMDcucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/07.png'><img loading=\"lazy\" decoding=\"async\" width=\"418\" height=\"286\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/07.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/07.png 418w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/07-300x205.png 300w\" sizes=\"(max-width: 418px) 100vw, 418px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"10\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTEzNCwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMTAucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/10.png'><img loading=\"lazy\" decoding=\"async\" width=\"418\" height=\"286\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/10.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/10.png 418w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/10-300x205.png 300w\" sizes=\"(max-width: 418px) 100vw, 418px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"11\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE1NSwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMTEucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/11.png'><img loading=\"lazy\" decoding=\"async\" width=\"418\" height=\"286\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/11.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/11.png 418w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/11-300x205.png 300w\" sizes=\"(max-width: 418px) 100vw, 418px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"12\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTEzNSwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMTIucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/12.png'><img loading=\"lazy\" decoding=\"async\" width=\"418\" height=\"286\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/12.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/12.png 418w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/12-300x205.png 300w\" sizes=\"(max-width: 418px) 100vw, 418px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"13\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE1NiwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMTMucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/13.png'><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"286\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/13.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/13.png 417w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/13-300x206.png 300w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"14\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTEzNiwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMTQucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/14.png'><img loading=\"lazy\" decoding=\"async\" width=\"418\" height=\"286\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/14.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/14.png 418w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/14-300x205.png 300w\" sizes=\"(max-width: 418px) 100vw, 418px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"15\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTEzNywidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMTUucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/15.png'><img loading=\"lazy\" decoding=\"async\" width=\"418\" height=\"285\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/15.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/15.png 418w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/15-300x205.png 300w\" sizes=\"(max-width: 418px) 100vw, 418px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"16\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTEzOCwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMTYucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/16.png'><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"285\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/16.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/16.png 417w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/16-300x205.png 300w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"17\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTEzOSwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMTcucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/17.png'><img loading=\"lazy\" decoding=\"async\" width=\"418\" height=\"285\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/17.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/17.png 418w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/17-300x205.png 300w\" sizes=\"(max-width: 418px) 100vw, 418px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"18\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE0MCwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMTgucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/18.png'><img loading=\"lazy\" decoding=\"async\" width=\"418\" height=\"285\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/18.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/18.png 418w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/18-300x205.png 300w\" sizes=\"(max-width: 418px) 100vw, 418px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"19\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE0MSwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMTkucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/19.png'><img loading=\"lazy\" decoding=\"async\" width=\"418\" height=\"285\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/19.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/19.png 418w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/19-300x205.png 300w\" sizes=\"(max-width: 418px) 100vw, 418px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"20\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE0MiwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMjAucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/20.png'><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"285\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/20.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/20.png 417w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/20-300x205.png 300w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"22\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE1NywidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMjIucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/22.png'><img loading=\"lazy\" decoding=\"async\" width=\"418\" height=\"286\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/22.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/22.png 418w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/22-300x205.png 300w\" sizes=\"(max-width: 418px) 100vw, 418px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"23\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE0MywidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMjMucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/23.png'><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"286\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/23.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/23.png 417w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/23-300x206.png 300w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"25\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE0NCwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMjUucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/25.png'><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"286\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/25.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/25.png 417w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/25-300x206.png 300w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"31\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE0NSwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMzEucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/31.png'><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"286\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/31.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/31.png 417w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/31-300x206.png 300w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE0NiwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMzIucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/32.png'><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"286\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/32.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/32.png 417w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/32-300x206.png 300w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"33\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE0NywidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMzMucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/33.png'><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"286\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/33.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/33.png 417w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/33-300x206.png 300w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"34\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE1OCwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvMzQucG5nIiwic2xpZGVzaG93IjoiZjE5M2FiNyJ9\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/34.png'><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"286\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/34.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/34.png 417w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/34-300x206.png 300w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"Emma_Mattress_Logo.svg\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE0OCwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvRW1tYV9NYXR0cmVzc19Mb2dvLnN2Zy5wbmciLCJzbGlkZXNob3ciOiJmMTkzYWI3In0%3D\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/Emma_Mattress_Logo.svg.png'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"629\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/Emma_Mattress_Logo.svg.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/Emma_Mattress_Logo.svg.png 2560w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/Emma_Mattress_Logo.svg-300x74.png 300w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/Emma_Mattress_Logo.svg-1024x252.png 1024w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/Emma_Mattress_Logo.svg-768x189.png 768w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/Emma_Mattress_Logo.svg-1536x377.png 1536w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/Emma_Mattress_Logo.svg-2048x503.png 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"Reach_plc_logo.svg\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE1MSwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvUmVhY2hfcGxjX2xvZ28uc3ZnLnBuZyIsInNsaWRlc2hvdyI6ImYxOTNhYjcifQ%3D%3D\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/Reach_plc_logo.svg.png'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"693\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/Reach_plc_logo.svg.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/Reach_plc_logo.svg.png 2560w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/Reach_plc_logo.svg-300x81.png 300w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/Reach_plc_logo.svg-1024x277.png 1024w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/Reach_plc_logo.svg-768x208.png 768w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/Reach_plc_logo.svg-1536x416.png 1536w, https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/Reach_plc_logo.svg-2048x554.png 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f193ab7\" data-elementor-lightbox-title=\"News_UK_logo\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE1MCwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbmdsZWFkdnQuY29tXC9sZW85XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNFwvTmV3c19VS19sb2dvLnN2ZyIsInNsaWRlc2hvdyI6ImYxOTNhYjcifQ%3D%3D\" href='https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/News_UK_logo.svg'><img loading=\"lazy\" decoding=\"async\" width=\"1347\" height=\"284\" src=\"https:\/\/www.angleadvt.com\/leo9\/wp-content\/uploads\/2025\/04\/News_UK_logo.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24c4f268 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24c4f268\" data-element_type=\"section\" id=\"contact\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-320de956\" data-id=\"320de956\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c527415 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c527415\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4963329\" data-id=\"4963329\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-401aae3 elementor-widget elementor-widget-heading\" data-id=\"401aae3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Get In Touch<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea19fab elementor-widget elementor-widget-metform\" data-id=\"ea19fab\" data-element_type=\"widget\" data-widget_type=\"metform.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"mf-response-props-id-3203\" data-previous-steps-style=\"\" data-editswitchopen=\"\" data-response_type=\"alert\" data-erroricon=\"fas fa-exclamation-triangle\" data-successicon=\"fas fa-check\" data-messageposition=\"top\" class=\"   mf-scroll-top-no\">\n\t\t<div class=\"formpicker_warper formpicker_warper_editable\" data-metform-formpicker-key=\"3203\" >\n\t\t\t\t\n\t\t\t<div class=\"mf-widget-container\">\n\t\t\t\t\r\n\t\t<div\r\n\t\t\tid=\"metform-wrap-ea19fab-3203\"\r\n\t\t\tclass=\"mf-form-wrapper\"\r\n\t\t\tdata-form-id=\"3203\"\r\n\t\t\tdata-action=\"https:\/\/www.angleadvt.com\/leo9\/wp-json\/metform\/v1\/entries\/insert\/3203\"\r\n\t\t\tdata-wp-nonce=\"7e2704fe45\"\r\n\t\t\tdata-form-nonce=\"40413e738c\"\r\n\t\t\tdata-quiz-summery = \"false\"\r\n\t\t\tdata-save-progress = \"false\"\r\n\t\t\tdata-form-type=\"general-form\"\r\n\t\t\tdata-stop-vertical-effect=\"\"\r\n\t\t\t><\/div>\r\n\r\n\r\n\t\t<!----------------------------- \r\n\t\t\t* controls_data : find the the props passed indie of data attribute\r\n\t\t\t* props.SubmitResponseMarkup : contains the markup of error or success message\r\n\t\t\t* https:\/\/developer.mozilla.org\/en-US\/docs\/Web\/JavaScript\/Reference\/Template_literals\r\n\t\t--------------------------- -->\r\n\r\n\t\t\t\t<script type=\"text\/mf\" class=\"mf-template\">\r\n\t\t\tfunction controls_data (value){\r\n\t\t\t\tlet currentWrapper = \"mf-response-props-id-3203\";\r\n\t\t\t\tlet currentEl = document.getElementById(currentWrapper);\r\n\t\t\t\t\r\n\t\t\t\treturn currentEl ? currentEl.dataset[value] : false\r\n\t\t\t}\r\n\r\n\r\n\t\t\tlet is_edit_mode = '' ? true : false;\r\n\t\t\tlet message_position = controls_data('messageposition') || 'top';\r\n\r\n\t\t\t\r\n\t\t\tlet message_successIcon = controls_data('successicon') || '';\r\n\t\t\tlet message_errorIcon = controls_data('erroricon') || '';\r\n\t\t\tlet message_editSwitch = controls_data('editswitchopen') === 'yes' ? true : false;\r\n\t\t\tlet message_proClass = controls_data('editswitchopen') === 'yes' ? 'mf_pro_activated' : '';\r\n\t\t\t\r\n\t\t\tlet is_dummy_markup = is_edit_mode && message_editSwitch ? true : false;\r\n\r\n\t\t\t\r\n\t\t\treturn html`\r\n\t\t\t\t<form\r\n\t\t\t\t\tclassName=\"metform-form-content\"\r\n\t\t\t\t\tref=${parent.formContainerRef}\r\n\t\t\t\t\tonSubmit=${ validation.handleSubmit( parent.handleFormSubmit ) }\r\n\t\t\t\t\r\n\t\t\t\t\t>\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'top' ?  props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' :  message_position === 'top' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\r\n\t\t\t\t\t<!--------------------------------------------------------\r\n\t\t\t\t\t*** IMPORTANT \/ DANGEROUS ***\r\n\t\t\t\t\t${html``} must be used as in immediate child of \"metform-form-main-wrapper\"\r\n\t\t\t\t\tclass otherwise multistep form will not run at all\r\n\t\t\t\t\t---------------------------------------------------------->\r\n\r\n\t\t\t\t\t<div className=\"metform-form-main-wrapper\" key=${'hide-form-after-submit'} ref=${parent.formRef}>\r\n\t\t\t\t\t${html`\r\n\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" key=\"2\" data-elementor-id=\"3203\" className=\"elementor elementor-3203\">\n\t\t\t\t\t\t<section className=\"elementor-section elementor-top-section elementor-element elementor-element-ad0fef4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad0fef4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aeb9fb7\" data-id=\"aeb9fb7\" data-element_type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-d4339fd elementor-widget elementor-widget-mf-email\" data-id=\"d4339fd\" data-element_type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;Email&quot;}\" data-widget_type=\"mf-email.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\r\n\t\t\t<input \r\n\t\t\t\ttype=\"email\" \r\n\t\t\t\t \r\n\t\t\t\tdefaultValue=\"\" \r\n\t\t\t\tclassName=\"mf-input \" \r\n\t\t\t\tid=\"mf-input-email-d4339fd\" \r\n\t\t\t\tname=\"Email\" \r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Email Address*`) } \" \r\n\t\t\t\t \r\n\t\t\t\tonBlur=${parent.handleChange} onFocus=${parent.handleChange} aria-invalid=${validation.errors['Email'] ? 'true' : 'false' } \r\n\t\t\t\tref=${el=> parent.activateValidation({\"message\":\"This field is required.\",\"emailMessage\":\"Please enter a valid Email address\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t<${validation.ErrorMessage} \r\n\t\t\t\terrors=${validation.errors} \r\n\t\t\t\tname=\"Email\" \r\n\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-ff7b985 elementor-widget elementor-widget-mf-text\" data-id=\"ff7b985\" data-element_type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;Subject&quot;}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input \"\r\n\t\t\t\tid=\"mf-input-text-ff7b985\"\r\n\t\t\t\tname=\"Subject\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Subject*`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['Subject'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"Subject\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-a342879 elementor-widget elementor-widget-mf-textarea\" data-id=\"a342879\" data-element_type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;your_question&quot;}\" data-widget_type=\"mf-textarea.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\r\n\t\t\t<textarea className=\"mf-input mf-textarea \" id=\"mf-input-text-area-a342879\"\r\n\t\t\t\tname=\"your_question\" \r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Your Question*`) } \"\r\n\t\t\t\tcols=\"30\" rows=\"10\"\r\n\t\t\t\t\t\t\t\t\tonInput=${ parent.handleChange }\r\n\t\t\t\t\taria-invalid=${validation.errors['your_question'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${ el => parent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\t><\/textarea>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"your_question\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-4608013 mf-btn--left elementor-widget elementor-widget-mf-button\" data-id=\"4608013\" data-element_type=\"widget\" data-widget_type=\"mf-button.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div className=\"mf-btn-wraper \" data-mf-form-conditional-logic-requirement=\"\">\r\n\t\t\t\t\t\t\t<button type=\"submit\" className=\"metform-btn metform-submit-btn \" id=\"\">\r\n\t\t\t\t\t<span>${ parent.decodeEntities(`Submit Button`) } <\/span>\r\n\t\t\t\t<\/button>\r\n\t\t\t        <\/div>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t`}\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'bottom' ? props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' : message_position === 'bottom' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\t\t\t\t\r\n\t\t\t\t<\/form>\r\n\t\t\t`\r\n\t\t<\/script>\r\n\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4153d0b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4153d0b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8625b5e\" data-id=\"8625b5e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9690c01 elementor-widget elementor-widget-text-editor\" data-id=\"9690c01\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tEmail:<br>\n<strong>hq@leo9advt.com<\/strong>\n<br><strong>business@leo9advt.com<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b2902e4\" data-id=\"b2902e4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e693ef6 elementor-widget elementor-widget-text-editor\" data-id=\"e693ef6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPhone:<br>\n<strong>+91 9881159141<\/strong>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3d21ba7\" data-id=\"3d21ba7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98b7494 elementor-widget elementor-widget-text-editor\" data-id=\"98b7494\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAddress:<br>\n<strong>Ingestre Court, Ingestre Pl, London W1F 0JL,\nUnited Kingdom<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>We are an end-to-end marketing firm building impactful relationships About us Who we are &#038; What we do Leo9 is the next chapter in the evolution of Angle Advertising, pushing into new markets while staying grounded in the creativity and expertise that have defined us. With offices across India and the UK, we\u2019re broadening our [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"tpl-default-elementor.php","meta":{"footnotes":""},"class_list":["post-4880","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.angleadvt.com\/leo9\/wp-json\/wp\/v2\/pages\/4880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.angleadvt.com\/leo9\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.angleadvt.com\/leo9\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.angleadvt.com\/leo9\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.angleadvt.com\/leo9\/wp-json\/wp\/v2\/comments?post=4880"}],"version-history":[{"count":350,"href":"https:\/\/www.angleadvt.com\/leo9\/wp-json\/wp\/v2\/pages\/4880\/revisions"}],"predecessor-version":[{"id":5563,"href":"https:\/\/www.angleadvt.com\/leo9\/wp-json\/wp\/v2\/pages\/4880\/revisions\/5563"}],"wp:attachment":[{"href":"https:\/\/www.angleadvt.com\/leo9\/wp-json\/wp\/v2\/media?parent=4880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}